{"id":23877,"date":"2024-06-03T15:33:53","date_gmt":"2024-06-03T13:33:53","guid":{"rendered":"https:\/\/befve.com\/?p=23877"},"modified":"2024-06-03T15:33:53","modified_gmt":"2024-06-03T13:33:53","slug":"varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune","status":"publish","type":"post","link":"https:\/\/befve.com\/en\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\/","title":{"rendered":"Varois-et-Chaignot. Ferme Dubois : 7 000 fourchettes \u00e0 planter \u00e0 la f\u00eate des Asperges vertes samedi Le Bien Public \u00ab Le marqueur de cette nouvelle f\u00eate des Asperges vertes sera la cr\u00e9ation d&#8217;une \u0153uvre artistique compos\u00e9e de 7 000 fourchettes \u00bb, explique Armelle Dubois"},"content":{"rendered":"<p><a href=\"https:\/\/www.bienpublic.com\/culture-loisirs\/2024\/05\/30\/ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi\">https:\/\/www.bienpublic.com\/culture-loisirs\/2024\/05\/30\/ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/www.bienpublic.com\/culture-loisirs\/2024\/05\/30\/ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi<\/p>\n","protected":false},"author":5,"featured_media":37267,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":0,"footnotes":""},"categories":[45,46],"tags":[],"class_list":["post-23877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mise-en-marche-vente","category-nouveautes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Varois-et-Chaignot. Ferme Dubois : 7 000 fourchettes \u00e0 planter \u00e0 la f\u00eate des Asperges vertes samedi Le Bien Public \u00ab Le marqueur de cette nouvelle f\u00eate des Asperges vertes sera la cr\u00e9ation d&#039;une \u0153uvre artistique compos\u00e9e de 7 000 fourchettes \u00bb, explique Armelle Dubois - Befve &amp; Co<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/befve.com\/en\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Varois-et-Chaignot. Ferme Dubois : 7 000 fourchettes \u00e0 planter \u00e0 la f\u00eate des Asperges vertes samedi Le Bien Public \u00ab Le marqueur de cette nouvelle f\u00eate des Asperges vertes sera la cr\u00e9ation d&#039;une \u0153uvre artistique compos\u00e9e de 7 000 fourchettes \u00bb, explique Armelle Dubois - Befve &amp; Co\" \/>\n<meta property=\"og:description\" content=\"https:\/\/www.bienpublic.com\/culture-loisirs\/2024\/05\/30\/ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/befve.com\/en\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\/\" \/>\n<meta property=\"og:site_name\" content=\"Befve &amp; Co\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-03T13:33:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2444\" \/>\n\t<meta property=\"og:image:height\" content=\"1020\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\\\/\"},\"author\":{\"name\":\"Lola\",\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/#\\\/schema\\\/person\\\/4ee575776823d7040f65f14cc647850f\"},\"headline\":\"Varois-et-Chaignot. Ferme Dubois : 7 000 fourchettes \u00e0 planter \u00e0 la f\u00eate des Asperges vertes samedi Le Bien Public \u00ab Le marqueur de cette nouvelle f\u00eate des Asperges vertes sera la cr\u00e9ation d&#8217;une \u0153uvre artistique compos\u00e9e de 7 000 fourchettes \u00bb, explique Armelle Dubois\",\"datePublished\":\"2024-06-03T13:33:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\\\/\"},\"wordCount\":48,\"publisher\":{\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/articles-1.jpg\",\"articleSection\":[\"Mise en march\u00e9, vente\",\"Nouveaut\u00e9s\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\\\/\",\"url\":\"https:\\\/\\\/befve.com\\\/en\\\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\\\/\",\"name\":\"Varois-et-Chaignot. Ferme Dubois : 7 000 fourchettes \u00e0 planter \u00e0 la f\u00eate des Asperges vertes samedi Le Bien Public \u00ab Le marqueur de cette nouvelle f\u00eate des Asperges vertes sera la cr\u00e9ation d'une \u0153uvre artistique compos\u00e9e de 7 000 fourchettes \u00bb, explique Armelle Dubois - Befve &amp; Co\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/articles-1.jpg\",\"datePublished\":\"2024-06-03T13:33:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/befve.com\\\/en\\\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\\\/#primaryimage\",\"url\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/articles-1.jpg\",\"contentUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/articles-1.jpg\",\"width\":2444,\"height\":1020,\"caption\":\"befve asperges\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/befve.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Varois-et-Chaignot. Ferme Dubois : 7 000 fourchettes \u00e0 planter \u00e0 la f\u00eate des Asperges vertes samedi Le Bien Public \u00ab Le marqueur de cette nouvelle f\u00eate des Asperges vertes sera la cr\u00e9ation d&#8217;une \u0153uvre artistique compos\u00e9e de 7 000 fourchettes \u00bb, explique Armelle Dubois\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/befve.com\\\/en\\\/\",\"name\":\"Befve &Co\",\"description\":\"Christian Befve expert &amp; consultant asperges\",\"publisher\":{\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/befve.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/#organization\",\"name\":\"Befve &Co\",\"alternateName\":\"Befve &Co\",\"url\":\"https:\\\/\\\/befve.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/logo_green.svg\",\"contentUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/logo_green.svg\",\"caption\":\"Befve &Co\"},\"image\":{\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/#\\\/schema\\\/person\\\/4ee575776823d7040f65f14cc647850f\",\"name\":\"Lola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2241487f462784423897bf42e4849904248a85d18d6f8c30d9f6414c4dada9a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2241487f462784423897bf42e4849904248a85d18d6f8c30d9f6414c4dada9a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2241487f462784423897bf42e4849904248a85d18d6f8c30d9f6414c4dada9a7?s=96&d=mm&r=g\",\"caption\":\"Lola\"},\"url\":\"https:\\\/\\\/befve.com\\\/en\\\/author\\\/lola\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Varois-et-Chaignot. Ferme Dubois : 7 000 fourchettes \u00e0 planter \u00e0 la f\u00eate des Asperges vertes samedi Le Bien Public \u00ab Le marqueur de cette nouvelle f\u00eate des Asperges vertes sera la cr\u00e9ation d'une \u0153uvre artistique compos\u00e9e de 7 000 fourchettes \u00bb, explique Armelle Dubois - Befve &amp; Co","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/befve.com\/en\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\/","og_locale":"en_US","og_type":"article","og_title":"Varois-et-Chaignot. Ferme Dubois : 7 000 fourchettes \u00e0 planter \u00e0 la f\u00eate des Asperges vertes samedi Le Bien Public \u00ab Le marqueur de cette nouvelle f\u00eate des Asperges vertes sera la cr\u00e9ation d'une \u0153uvre artistique compos\u00e9e de 7 000 fourchettes \u00bb, explique Armelle Dubois - Befve &amp; Co","og_description":"https:\/\/www.bienpublic.com\/culture-loisirs\/2024\/05\/30\/ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi","og_url":"https:\/\/befve.com\/en\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\/","og_site_name":"Befve &amp; Co","article_published_time":"2024-06-03T13:33:53+00:00","og_image":[{"width":2444,"height":1020,"url":"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg","type":"image\/jpeg"}],"author":"Lola","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Lola","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/befve.com\/en\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\/#article","isPartOf":{"@id":"https:\/\/befve.com\/en\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\/"},"author":{"name":"Lola","@id":"https:\/\/befve.com\/en\/#\/schema\/person\/4ee575776823d7040f65f14cc647850f"},"headline":"Varois-et-Chaignot. Ferme Dubois : 7 000 fourchettes \u00e0 planter \u00e0 la f\u00eate des Asperges vertes samedi Le Bien Public \u00ab Le marqueur de cette nouvelle f\u00eate des Asperges vertes sera la cr\u00e9ation d&#8217;une \u0153uvre artistique compos\u00e9e de 7 000 fourchettes \u00bb, explique Armelle Dubois","datePublished":"2024-06-03T13:33:53+00:00","mainEntityOfPage":{"@id":"https:\/\/befve.com\/en\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\/"},"wordCount":48,"publisher":{"@id":"https:\/\/befve.com\/en\/#organization"},"image":{"@id":"https:\/\/befve.com\/en\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\/#primaryimage"},"thumbnailUrl":"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg","articleSection":["Mise en march\u00e9, vente","Nouveaut\u00e9s"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/befve.com\/en\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\/","url":"https:\/\/befve.com\/en\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\/","name":"Varois-et-Chaignot. Ferme Dubois : 7 000 fourchettes \u00e0 planter \u00e0 la f\u00eate des Asperges vertes samedi Le Bien Public \u00ab Le marqueur de cette nouvelle f\u00eate des Asperges vertes sera la cr\u00e9ation d'une \u0153uvre artistique compos\u00e9e de 7 000 fourchettes \u00bb, explique Armelle Dubois - Befve &amp; Co","isPartOf":{"@id":"https:\/\/befve.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/befve.com\/en\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\/#primaryimage"},"image":{"@id":"https:\/\/befve.com\/en\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\/#primaryimage"},"thumbnailUrl":"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg","datePublished":"2024-06-03T13:33:53+00:00","breadcrumb":{"@id":"https:\/\/befve.com\/en\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/befve.com\/en\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/befve.com\/en\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\/#primaryimage","url":"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg","contentUrl":"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg","width":2444,"height":1020,"caption":"befve asperges"},{"@type":"BreadcrumbList","@id":"https:\/\/befve.com\/en\/varois-et-chaignot-ferme-dubois-7-000-fourchettes-a-planter-a-la-fete-des-asperges-vertes-samedi-le-bien-public-le-marqueur-de-cette-nouvelle-fete-des-asperges-vertes-sera-la-creation-dune\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/befve.com\/en\/"},{"@type":"ListItem","position":2,"name":"Varois-et-Chaignot. Ferme Dubois : 7 000 fourchettes \u00e0 planter \u00e0 la f\u00eate des Asperges vertes samedi Le Bien Public \u00ab Le marqueur de cette nouvelle f\u00eate des Asperges vertes sera la cr\u00e9ation d&#8217;une \u0153uvre artistique compos\u00e9e de 7 000 fourchettes \u00bb, explique Armelle Dubois"}]},{"@type":"WebSite","@id":"https:\/\/befve.com\/en\/#website","url":"https:\/\/befve.com\/en\/","name":"Befve &Co","description":"Christian Befve expert &amp; consultant asperges","publisher":{"@id":"https:\/\/befve.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/befve.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/befve.com\/en\/#organization","name":"Befve &Co","alternateName":"Befve &Co","url":"https:\/\/befve.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/befve.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/befve.com\/wp-content\/uploads\/logo_green.svg","contentUrl":"https:\/\/befve.com\/wp-content\/uploads\/logo_green.svg","caption":"Befve &Co"},"image":{"@id":"https:\/\/befve.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/befve.com\/en\/#\/schema\/person\/4ee575776823d7040f65f14cc647850f","name":"Lola","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/2241487f462784423897bf42e4849904248a85d18d6f8c30d9f6414c4dada9a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2241487f462784423897bf42e4849904248a85d18d6f8c30d9f6414c4dada9a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2241487f462784423897bf42e4849904248a85d18d6f8c30d9f6414c4dada9a7?s=96&d=mm&r=g","caption":"Lola"},"url":"https:\/\/befve.com\/en\/author\/lola\/"}]}},"_links":{"self":[{"href":"https:\/\/befve.com\/en\/wp-json\/wp\/v2\/posts\/23877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/befve.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/befve.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/befve.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/befve.com\/en\/wp-json\/wp\/v2\/comments?post=23877"}],"version-history":[{"count":0,"href":"https:\/\/befve.com\/en\/wp-json\/wp\/v2\/posts\/23877\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/befve.com\/en\/wp-json\/wp\/v2\/media\/37267"}],"wp:attachment":[{"href":"https:\/\/befve.com\/en\/wp-json\/wp\/v2\/media?parent=23877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/befve.com\/en\/wp-json\/wp\/v2\/categories?post=23877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/befve.com\/en\/wp-json\/wp\/v2\/tags?post=23877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}