{"id":265883,"date":"2026-04-13T14:18:21","date_gmt":"2026-04-13T14:18:21","guid":{"rendered":"https:\/\/befve.com\/?p=265883"},"modified":"2026-04-13T14:18:22","modified_gmt":"2026-04-13T14:18:22","slug":"marche-mondial-la-fraise-par-freshplaza","status":"publish","type":"post","link":"https:\/\/befve.com\/en\/marche-mondial-la-fraise-par-freshplaza\/","title":{"rendered":"March\u00e9 mondial : la fraise par FreshPlaza"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">March\u00e9 mondial : la fraise<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">Le march\u00e9 mondial des fraises entre dans une phase o\u00f9 le timing, et non le volume seul, d\u00e9termine les r\u00e9sultats. Dans toutes les r\u00e9gions, l&#8217;offre augmente, mais pas toujours au bon moment, avec la bonne qualit\u00e9 et des prix qui refl\u00e8tent l&#8217;augmentation des co\u00fbts. Ce qui appara\u00eet en surface comme une reprise de la disponibilit\u00e9 masque, dans de nombreux cas, des d\u00e9s\u00e9quilibres plus profonds entre la production, les fen\u00eatres de march\u00e9 et les pressions exerc\u00e9es par les intrants.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.freshplaza.fr\/remote\/https\/agfstorage.blob.core.windows.net\/misc\/FP_fr\/2026\/04\/10\/wk15_Strawberries_FR.jpg?preset=ContentFullSmall\" alt=\"\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Au fur et \u00e0 mesure que la saison se d\u00e9roule, depuis les premi\u00e8res r\u00e9coltes europ\u00e9ennes jusqu&#8217;aux volumes maximaux en Am\u00e9rique du Nord et \u00e0 l&#8217;offre \u00e9mergente dans l&#8217;h\u00e9misph\u00e8re sud, les producteurs et n\u00e9gociants naviguent sur un march\u00e9 o\u00f9 les conditions m\u00e9t\u00e9o, l&#8217;inflation des co\u00fbts et l&#8217;\u00e9volution de la demande sont de plus en plus interconnect\u00e9es. Il en r\u00e9sulte une campagne moins marqu\u00e9e par les p\u00e9nuries ou les exc\u00e9dents que par l&#8217;efficacit\u00e9 avec laquelle chaque r\u00e9gion peut aligner l&#8217;offre sur les attentes du march\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pays-Bas : les prix ne suivent pas la hausse des co\u00fbts<br><\/strong>\u00ab P\u00e2ques reste un point de r\u00e9f\u00e9rence cl\u00e9 sur le march\u00e9 des fraises, marquant le d\u00e9but de la saison n\u00e9erlandaise. \u00c0 l&#8217;approche des f\u00eates, il y a toujours une p\u00e9nurie \u00bb, explique un producteur n\u00e9erlandais. \u00ab Nous entamons actuellement la saison Elsanta, qui \u00e9tait auparavant la vari\u00e9t\u00e9 standard. Mais nous avons d\u00e9j\u00e0 plusieurs semaines de r\u00e9colte de remontantes pendant plusieurs derri\u00e8re nous et avons donc d\u00e9j\u00e0 pu servir nos clients norv\u00e9giens en particulier. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le producteur d\u00e9crit l&#8217;expansion des vari\u00e9t\u00e9s remontantes comme un avantage majeur. \u00ab Elles nous permettent d&#8217;obtenir un sch\u00e9ma de production beaucoup plus r\u00e9gulier et d&#8217;offrir aux d\u00e9taillants des programmes plus solides ainsi qu&#8217;un produit plus fiable. En avril et en mai, il y aura encore des pics de production, mais la culture des fraises tend \u00e0 s&#8217;\u00e9taler sur toute l&#8217;ann\u00e9e, avec un approvisionnement continu. Cela permet de fournir des volumes plus importants au march\u00e9. Dans des conditions de culture optimales, nous sommes en mesure de produire tout au long de l&#8217;ann\u00e9e. Cette saison, nous avons connu un trou de 3 \u00e0 4 semaines. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le m\u00eame temps, les d\u00e9fis restent nombreux, notamment en raison de l&#8217;augmentation des co\u00fbts de l&#8217;\u00e9nergie. \u00ab Si cette tendance se poursuit, la production de fraises d&#8217;hiver deviendra beaucoup plus difficile. Si les prix actuels du march\u00e9 sont suffisants pour vendre nos fraises, ils ne sont pas assez \u00e9lev\u00e9s pour soutenir le d\u00e9veloppement de la culture, car les prix des fraises ne suivent pas le rythme de l&#8217;augmentation des co\u00fbts, ce qui exerce une pression consid\u00e9rable sur le march\u00e9. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Belgique : les volumes augmentent avec la stabilisation des prix<br><\/strong>Apr\u00e8s une phase initiale marqu\u00e9e par des volumes moindres, les cultures non \u00e9clair\u00e9es sont d\u00e9sormais pleinement entr\u00e9es en production. \u00ab Cela signifie que les volumes augmentent rapidement, mais dans les premi\u00e8res semaines, ils d\u00e9pendent fortement des conditions m\u00e9t\u00e9orologiques \u00bb, d\u00e9clare un n\u00e9gociant belge. \u00ab Jusqu&#8217;\u00e0 P\u00e2ques, l&#8217;offre semblait suffisante. Puis le temps s&#8217;est g\u00e2t\u00e9 et les prix ont imm\u00e9diatement augment\u00e9. Aujourd&#8217;hui, de bons volumes arrivent sur le march\u00e9 \u00e0 des prix qui conviennent \u00e0 tout le monde. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab La demande pour les petits fruits locaux est intense, notamment en raison des probl\u00e8mes de qualit\u00e9 ces derniers mois en Espagne, au Portugal et au Maroc. Maintenant que le produit local est l\u00e0, il se vend rapidement sur le march\u00e9 domestique, et en exportons dans toute l&#8217;Europe du Nord. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Italie : la zone s&#8217;\u00e9tend alors que les prix sont sous pression<\/strong><br>Dans l&#8217;ensemble, les perspectives pour la campagne 2026 sont positives, caract\u00e9ris\u00e9es par une augmentation de la superficie cultiv\u00e9e, en particulier en Italie et en Espagne, et une croissance continue du secteur. Les rendements varient en fonction des vari\u00e9t\u00e9s et des m\u00e9thodes de culture utilis\u00e9es, allant d&#8217;environ 27 000 kg\/ha dans les syst\u00e8mes en terre \u00e0 plus de 50 000 \u00e0 68 000 kg\/ha dans les syst\u00e8mes sans terre. En Italie, la superficie cultiv\u00e9e a augment\u00e9 d&#8217;environ 250 ha, ce qui confirme le d\u00e9veloppement du secteur. Parall\u00e8lement, les zones de production se d\u00e9placent vers le sud du pays. En Campanie, la culture continue de s&#8217;\u00e9tendre, augmentant de 6 % par rapport \u00e0 l&#8217;ann\u00e9e derni\u00e8re pour atteindre plus de 1 200 ha. En Basilicate, la superficie cultiv\u00e9e a augment\u00e9 de 17 % par rapport \u00e0 2025, pour atteindre environ 1 280 ha. Ensemble, ces deux r\u00e9gions repr\u00e9sentent 2 500 ha, soit 56 % du total national. Parall\u00e8lement, les surfaces cultiv\u00e9es en Calabre ont diminu\u00e9 de 4 %, tandis que celles de la Sicile ont l\u00e9g\u00e8rement augment\u00e9 de 2 %. Dans le nord, la superficie totale cultiv\u00e9e est estim\u00e9e \u00e0 un peu plus de 900 ha en 2026, ce qui repr\u00e9sente une diminution de 1 %.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au cours de la semaine 14, le prix de gros des fraises a chut\u00e9 de 11,2 % par rapport aux sept jours pr\u00e9c\u00e9dents. L&#8217;abondance de la production espagnole, vendue \u00e0 des prix allant de 2,50 \u00e0 2,80 \u20ac\/kg, a exerc\u00e9 une pression \u00e0 la baisse sur les vari\u00e9t\u00e9s italiennes. La production de la r\u00e9gion de Campanie se vend entre 3 et 3,50 \u20ac\/kg, tandis que les fraises siciliennes se vendent \u00e0 environ 4 \u20ac\/kg. La vari\u00e9t\u00e9 Sabrosa de Basilicate est vendue \u00e0 environ 5 \u20ac\/kg, tandis que la vari\u00e9t\u00e9 Inspire est vendue entre 5 et 6 \u20ac\/kg.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Selon les donn\u00e9es de YouGov, plus de 70 % des m\u00e9nages italiens ach\u00e8tent des fraises. La fr\u00e9quence d&#8217;achat augmente, le nombre moyen d&#8217;achats passant d&#8217;environ 6,2 \u00e0 7,1 par an, soit une augmentation de 9 %. Les supermarch\u00e9s et les magasins discount restent les principaux points d&#8217;achat. Bien qu&#8217;en croissance, le segment des fraises bio reste limit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Espagne : impact des conditions m\u00e9t\u00e9orologiques et baisse des prix<\/strong><br>La saison en Espagne s&#8217;av\u00e8re \u00eatre l&#8217;une des plus difficiles de ces derni\u00e8res ann\u00e9es. Au cours des premiers mois, jusqu&#8217;\u00e0 la mi-f\u00e9vrier, elle a \u00e9t\u00e9 affect\u00e9e par de fortes pr\u00e9cipitations, des temp\u00e9ratures plus froides et des vents violents, qui ont endommag\u00e9 les infrastructures des serres et fortement r\u00e9duit la disponibilit\u00e9 des fruits, parfois de plus de la moiti\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;offre est rest\u00e9e tr\u00e8s limit\u00e9e jusqu&#8217;\u00e0 la mi-mars, traversant la p\u00e9riode de la Saint-Valentin, o\u00f9 les commandes augmentent habituellement, sans pouvoir r\u00e9pondre \u00e0 la demande. Pendant cette p\u00e9riode de p\u00e9nurie, une grande partie des exp\u00e9ditions est rest\u00e9e sur le march\u00e9 int\u00e9rieur et au Portugal en raison des risques associ\u00e9s \u00e0 l&#8217;exportation sur de longues distances, en particulier les probl\u00e8mes de qualit\u00e9 caus\u00e9s par l&#8217;exc\u00e8s d&#8217;humidit\u00e9. Dans ce contexte, les fraises grecques ont gagn\u00e9 du terrain sur le march\u00e9 avec des fruits moins chers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avec l&#8217;am\u00e9lioration des conditions m\u00e9t\u00e9orologiques en mars, la production \u00e0 Huelva a commenc\u00e9 \u00e0 se redresser. Toutefois, depuis la fin du mois de mars, les exportateurs espagnols ont perdu leur position sur le march\u00e9 et ont \u00e9t\u00e9 contraints de r\u00e9duire fortement les prix pour vendre leurs fruits, tombant ainsi en dessous des niveaux de rentabilit\u00e9. Cette situation survient \u00e0 un moment o\u00f9 les co\u00fbts du carburant et d&#8217;autres intrants ont augment\u00e9. Outre la Gr\u00e8ce, la production provient \u00e9galement d&#8217;Italie, de France et des Pays-Bas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Les premiers mois de la saison repr\u00e9sentent le moment o\u00f9 les exportateurs espagnols peuvent gagner le plus d&#8217;argent parce que les disponibilit\u00e9s en Europe sont moindres. Cependant, cette ann\u00e9e, nous n&#8217;avons pratiquement pas eu de production. Aujourd&#8217;hui, nous sommes confront\u00e9s \u00e0 une offre abondante \u00e0 des prix d\u00e9fiant toute concurrence \u00bb, a d\u00e9clar\u00e9 un producteur et exportateur de Huelva. \u00ab Nous nous attendons \u00e0 ce que la production diminue en avril, puis augmente \u00e0 nouveau en mai, mais si cette tendance \u00e0 la baisse se poursuit, de nombreuses exploitations risquent de ne pas r\u00e9colter, car elles perdraient de l&#8217;argent compte tenu des co\u00fbts de r\u00e9colte. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Allemagne : les importations dominent et la saison nationale commence lentement<\/strong><br>La gamme de fraises r\u00e9cemment disponible sur le march\u00e9 de gros allemand \u00e9tait large, avec des produits provenant des Pays-Bas, de Belgique, de Gr\u00e8ce, d&#8217;Italie et d&#8217;Espagne. Les premi\u00e8res fraises provenant des serres nationales ont sporadiquement commenc\u00e9 \u00e0 appara\u00eetre fin mars. Apr\u00e8s des semaines de p\u00e9nurie, l&#8217;offre de fraises espagnoles en provenance de la r\u00e9gion de Huelva a repris \u00e0 la fin du mois de mars, bien que les volumes totaux soient rest\u00e9s inf\u00e9rieurs \u00e0 ceux de l&#8217;ann\u00e9e derni\u00e8re. N\u00e9anmoins, les ventes ont clairement b\u00e9n\u00e9fici\u00e9 du commerce de P\u00e2ques. Par ailleurs, les fournisseurs grecs et n\u00e9erlandais font \u00e9tat de niveaux d&#8217;approvisionnement satisfaisants. Les prix dans toute la gamme sont sup\u00e9rieurs \u00e0 ceux de l&#8217;ann\u00e9e derni\u00e8re.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les premi\u00e8res quantit\u00e9s significatives de fraises provenant des cultures de plein champ allemandes sont attendues autour du 20 avril, selon les derni\u00e8res informations de l&#8217;association de producteurs VSSE. La saison commence traditionnellement dans la r\u00e9gion d&#8217;Oberkirch, dans le sud-ouest de l&#8217;Allemagne. Selon la VSSE, les fraisiers sous tunnels sont actuellement en fleurs. La croissance s&#8217;est ralentie en raison des basses temp\u00e9ratures et de l&#8217;ensoleillement limit\u00e9 des semaines 13 et 14, ajoute le rapport.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Royaume-Uni : l&#8217;offre pr\u00e9coce s&#8217;accro\u00eet \u00e0 l&#8217;approche de la pleine saison<br><\/strong>Les fruits provenant des serres sont disponibles depuis un certain temps, et la production pr\u00e9coce sous tunnel a maintenant commenc\u00e9, les volumes augmentant \u00e0 la suite du temps favorable de cette semaine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La principale saison des fraises au Royaume-Uni devrait commencer fin avril ou d\u00e9but mai si le temps favorable se maintient. La saison n\u00e9erlandaise a commenc\u00e9 un peu plus t\u00f4t cette ann\u00e9e, avec de bons volumes disponibles. Les prix semblent stables et devraient diminuer \u00e0 mesure que les volumes augmentent. Un importateur esp\u00e8re que la saison n\u00e9erlandaise sera plus stable et moins difficile que la saison espagnole.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les prix des fruits sont rest\u00e9s inchang\u00e9s, mais les co\u00fbts de transport ont augment\u00e9 depuis le d\u00e9but du conflit au Moyen-Orient. Les co\u00fbts du fret a\u00e9rien ont augment\u00e9, de m\u00eame que les prix du transport routier. L&#8217;importateur indique que ces co\u00fbts sont actuellement absorb\u00e9s, mais que cela ne peut \u00eatre maintenu sur une longue p\u00e9riode.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>France : les volumes de Gariguette d\u00e9passent les 1 000 tonnes par semaine<\/strong><br>La saison fran\u00e7aise arrive \u00e0 un tournant d\u00e9cisif, la production de gariguettes d\u00e9passant d\u00e9sormais 1 000 tonnes par semaine \u00e0 la suite de l&#8217;am\u00e9lioration des conditions m\u00e9t\u00e9o. Cela fait suite \u00e0 un d\u00e9marrage retard\u00e9 et \u00e0 des p\u00e9nuries d&#8217;approvisionnement ant\u00e9rieures caus\u00e9es par des temp\u00e9ratures froides et du vent. Le march\u00e9 a \u00e9galement subi la pression des importations espagnoles \u00e0 bas prix, qui a cr\u00e9\u00e9 des probl\u00e8mes de prix pour les fruits fran\u00e7ais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour l&#8217;instant, les ventes restent relativement bonnes, bien qu&#8217;il y ait de grandes diff\u00e9rences de prix dans les supermarch\u00e9s pour le m\u00eame produit, les fraises gariguettes fran\u00e7aises allant de 2,5 \u00e0 5 \u20ac. Dans les semaines \u00e0 venir, l&#8217;augmentation des volumes, en particulier des fraises rondes, rendra les niveaux de consommation importants pour assurer la fluidit\u00e9 des ventes et maintenir l&#8217;\u00e9quilibre du march\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Am\u00e9rique du Nord : l&#8217;offre d\u00e9passe la demande dans toutes les r\u00e9gions<\/strong><br>L&#8217;offre de fraises aux \u00c9tats-Unis est actuellement importante. En Californie, Santa Maria signale des niveaux de production \u00e9lev\u00e9s, avec des fruits de bonne saveur et de bonne couleur. Le pic de l&#8217;offre conventionnelle est en cours et devrait se poursuivre jusqu&#8217;\u00e0 la semaine 19. En bio, il est est pr\u00e9vu entre les semaines 16 et 20.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oxnard et Salinas-Watsonville sont \u00e9galement en production. Dans les r\u00e9gions de culture de la Californie, les cultures se sont d\u00e9velopp\u00e9es au cours d&#8217;un hiver plus chaud que la normale, associ\u00e9 \u00e0 des pr\u00e9cipitations r\u00e9guli\u00e8res. En cons\u00e9quence, des r\u00e9gions telles que Salinas-Watsonville devraient produire davantage que l&#8217;ann\u00e9e derni\u00e8re \u00e0 la m\u00eame \u00e9poque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Floride a termin\u00e9 sa saison. Plus t\u00f4t dans l&#8217;ann\u00e9e, les producteurs ont \u00e9t\u00e9 affect\u00e9s par les gel\u00e9es de fin janvier et de d\u00e9but f\u00e9vrier, mais l&#8217;offre s&#8217;est r\u00e9tablie plus r\u00e9cemment. La r\u00e9gion de Baja est en grande partie termin\u00e9e, bien que l&#8217;on signale que certains fruits traversent encore la fronti\u00e8re.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre-temps, l&#8217;offre d\u00e9passe la demande. Le march\u00e9 bio a \u00e9t\u00e9 plus faible que pr\u00e9vu, alors que l&#8217;on s&#8217;attend \u00e0 ce que le march\u00e9 conventionnel se renforce. Certains rapports indiquent que certains exp\u00e9diteurs de Santa Maria n&#8217;emballent pas pendant le premier ou les deux premiers jours apr\u00e8s P\u00e2ques afin de soutenir le march\u00e9. Le mois d&#8217;avril devrait \u00eatre un mois charg\u00e9 pour les promotions de fraises.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Afrique du Sud : les plantations tardives retardent l&#8217;approvisionnement local<\/strong><br>En raison des pluies prolong\u00e9es, les producteurs ont plant\u00e9 un peu plus tard que d&#8217;habitude, et les premi\u00e8res fraises locales sont arriv\u00e9es cette semaine sur le march\u00e9 de Johannesburg, selon un n\u00e9gociant. \u00ab Nous avons eu un peu de fraises import\u00e9es, maintenant nous allons passer aux producteurs locaux. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une barquette de 250 g de fraises se n\u00e9gocie actuellement sur le march\u00e9 de gros entre 2,37 et 2,97 \u20ac, ce qui est excellent. Toutefois, ce niveau ne devrait durer que quelques semaines, jusqu&#8217;\u00e0 ce que les volumes augmentent. Selon le site web du march\u00e9 de Johannesburg, les fraises, dont la disponibilit\u00e9 est extr\u00eamement limit\u00e9e \u00e0 l&#8217;heure actuelle, se vendent \u00e0 10,74 \u20ac\/kg.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Moyen-Orient fait d\u00e9sormais partie int\u00e9grante de la campagne d&#8217;exportation de fraises de l&#8217;Afrique du Sud, et un exportateur indique que les exp\u00e9ditions devraient commencer cette semaine ou la suivante. La r\u00e9ouverture du d\u00e9troit d&#8217;Ormuz serait donc plus que le bienvenu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c9gypte : pression des co\u00fbts et variabilit\u00e9 de la qualit\u00e9<\/strong><br>Le secteur \u00e9gyptien des fraises congel\u00e9es fait \u00e9tat de volumes stables, mais de difficult\u00e9s persistantes en mati\u00e8re d&#8217;uniformit\u00e9 et de contr\u00f4le des co\u00fbts. Selon un exportateur, les surfaces et les volumes sont en place, mais les conditions m\u00e9t\u00e9orologiques variables affectent la fiabilit\u00e9 des fruits. \u00ab Le march\u00e9 ne manque pas de fraises, mais de fruits sur lesquelles on peut vraiment compter \u00bb, d\u00e9clare Reham Suhry, directrice g\u00e9n\u00e9rale de l&#8217;exportateur \u00e9gyptien de fraises Egyberries.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les exportateurs se concentrent sur un contr\u00f4le plus \u00e9troit au niveau de l&#8217;exploitation, sur la tra\u00e7abilit\u00e9 et sur la s\u00e9lection des fournisseurs pour g\u00e9rer la variabilit\u00e9. Dans le m\u00eame temps, les co\u00fbts des intrants ont augment\u00e9 : le carburant a augment\u00e9 d&#8217;environ 30 %, l&#8217;\u00e9lectricit\u00e9 de 15 \u00e0 20 % et les co\u00fbts d&#8217;emballage de 50 %.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les acheteurs mettent plus de temps \u00e0 prendre leurs d\u00e9cisions, ce qui se traduit par des p\u00e9riodes de stockage plus longues et des co\u00fbts de financement plus \u00e9lev\u00e9s. Les impacts indirects des march\u00e9s mondiaux du transport maritime et de l&#8217;\u00e9nergie affectent \u00e9galement la planification logistique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En r\u00e9action, les exportateurs r\u00e9duisent leur base de fournisseurs et donnent la priorit\u00e9 \u00e0 la gestion de la qualit\u00e9 et \u00e0 la conformit\u00e9. Les conditions du march\u00e9 devraient rester inchang\u00e9es \u00e0 court terme, avec une pression continue sur les co\u00fbts et une variabilit\u00e9 de l&#8217;offre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a9 <a href=\"https:\/\/www.FreshPlaza.fr\">FreshPlaza.fr<\/a> \/ <a href=\"mailto:stefan@agfnl.onmicrosoft.com?subject=Reactie op March\u00e9 mondial : la fraise\">Stefan Jansen van Nieuwenhuizen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>March\u00e9 mondial : la fraise Le march\u00e9 mondial des fraises entre dans une phase o\u00f9 le timing, et non le volume seul, d\u00e9termine les r\u00e9sultats. Dans toutes les r\u00e9gions, l&#8217;offre augmente, mais pas toujours au bon moment, avec la bonne qualit\u00e9 et des prix qui refl\u00e8tent l&#8217;augmentation des co\u00fbts. Ce qui appara\u00eet en surface comme [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":266085,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":13,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-265883","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorise"],"acf":[],"featured_image_url":{"thumbnail":"https:\/\/befve.com\/wp-content\/uploads\/2026\/05\/articles-Christian-Befve-150x150.jpg","medium":"https:\/\/befve.com\/wp-content\/uploads\/2026\/05\/articles-Christian-Befve-300x60.jpg","medium_large":"https:\/\/befve.com\/wp-content\/uploads\/2026\/05\/articles-Christian-Befve-768x154.jpg","large":"https:\/\/befve.com\/wp-content\/uploads\/2026\/05\/articles-Christian-Befve-1024x205.jpg","1536x1536":"https:\/\/befve.com\/wp-content\/uploads\/2026\/05\/articles-Christian-Befve-1536x307.jpg","2048x2048":"https:\/\/befve.com\/wp-content\/uploads\/2026\/05\/articles-Christian-Befve-2048x410.jpg"},"post_author":"Christian","assigned_categories":"Non cat\u00e9goris\u00e9","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>March\u00e9 mondial : la fraise par FreshPlaza - Befve &amp; Co<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/befve.com\/en\/marche-mondial-la-fraise-par-freshplaza\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"March\u00e9 mondial : la fraise par FreshPlaza - Befve &amp; Co\" \/>\n<meta property=\"og:description\" content=\"March\u00e9 mondial : la fraise Le march\u00e9 mondial des fraises entre dans une phase o\u00f9 le timing, et non le volume seul, d\u00e9termine les r\u00e9sultats. Dans toutes les r\u00e9gions, l&#8217;offre augmente, mais pas toujours au bon moment, avec la bonne qualit\u00e9 et des prix qui refl\u00e8tent l&#8217;augmentation des co\u00fbts. Ce qui appara\u00eet en surface comme [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/befve.com\/en\/marche-mondial-la-fraise-par-freshplaza\/\" \/>\n<meta property=\"og:site_name\" content=\"Befve &amp; Co\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-13T14:18:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-13T14:18:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/befve.com\/wp-content\/uploads\/2026\/05\/articles-Christian-Befve-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/marche-mondial-la-fraise-par-freshplaza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/marche-mondial-la-fraise-par-freshplaza\\\/\"},\"author\":{\"name\":\"Christian\",\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/#\\\/schema\\\/person\\\/ef49a1871aa7378da9d8d3cd2875d9b3\"},\"headline\":\"March\u00e9 mondial : la fraise par FreshPlaza\",\"datePublished\":\"2026-04-13T14:18:21+00:00\",\"dateModified\":\"2026-04-13T14:18:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/marche-mondial-la-fraise-par-freshplaza\\\/\"},\"wordCount\":2661,\"publisher\":{\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/marche-mondial-la-fraise-par-freshplaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/articles-Christian-Befve-scaled.jpg\",\"articleSection\":[\"Non cat\u00e9goris\u00e9\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/marche-mondial-la-fraise-par-freshplaza\\\/\",\"url\":\"https:\\\/\\\/befve.com\\\/en\\\/marche-mondial-la-fraise-par-freshplaza\\\/\",\"name\":\"March\u00e9 mondial : la fraise par FreshPlaza - Befve &amp; Co\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/marche-mondial-la-fraise-par-freshplaza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/marche-mondial-la-fraise-par-freshplaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/articles-Christian-Befve-scaled.jpg\",\"datePublished\":\"2026-04-13T14:18:21+00:00\",\"dateModified\":\"2026-04-13T14:18:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/marche-mondial-la-fraise-par-freshplaza\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/befve.com\\\/en\\\/marche-mondial-la-fraise-par-freshplaza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/marche-mondial-la-fraise-par-freshplaza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/articles-Christian-Befve-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/articles-Christian-Befve-scaled.jpg\",\"width\":2560,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/marche-mondial-la-fraise-par-freshplaza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/befve.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"March\u00e9 mondial : la fraise par FreshPlaza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/befve.com\\\/en\\\/\",\"name\":\"Befve &Co\",\"description\":\"Christian Befve expert &amp; consultant asperges\",\"publisher\":{\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/befve.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/#organization\",\"name\":\"Befve &Co\",\"alternateName\":\"Befve &Co\",\"url\":\"https:\\\/\\\/befve.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/logo_green.svg\",\"contentUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/logo_green.svg\",\"caption\":\"Befve &Co\"},\"image\":{\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/befve.com\\\/en\\\/#\\\/schema\\\/person\\\/ef49a1871aa7378da9d8d3cd2875d9b3\",\"name\":\"Christian\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g\",\"caption\":\"Christian\"},\"url\":\"https:\\\/\\\/befve.com\\\/en\\\/author\\\/christian\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"March\u00e9 mondial : la fraise par FreshPlaza - Befve &amp; Co","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/befve.com\/en\/marche-mondial-la-fraise-par-freshplaza\/","og_locale":"en_US","og_type":"article","og_title":"March\u00e9 mondial : la fraise par FreshPlaza - Befve &amp; Co","og_description":"March\u00e9 mondial : la fraise Le march\u00e9 mondial des fraises entre dans une phase o\u00f9 le timing, et non le volume seul, d\u00e9termine les r\u00e9sultats. Dans toutes les r\u00e9gions, l&#8217;offre augmente, mais pas toujours au bon moment, avec la bonne qualit\u00e9 et des prix qui refl\u00e8tent l&#8217;augmentation des co\u00fbts. Ce qui appara\u00eet en surface comme [&hellip;]","og_url":"https:\/\/befve.com\/en\/marche-mondial-la-fraise-par-freshplaza\/","og_site_name":"Befve &amp; Co","article_published_time":"2026-04-13T14:18:21+00:00","article_modified_time":"2026-04-13T14:18:22+00:00","og_image":[{"width":2560,"height":512,"url":"https:\/\/befve.com\/wp-content\/uploads\/2026\/05\/articles-Christian-Befve-scaled.jpg","type":"image\/jpeg"}],"author":"Christian","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Christian","Est. reading time":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/befve.com\/en\/marche-mondial-la-fraise-par-freshplaza\/#article","isPartOf":{"@id":"https:\/\/befve.com\/en\/marche-mondial-la-fraise-par-freshplaza\/"},"author":{"name":"Christian","@id":"https:\/\/befve.com\/en\/#\/schema\/person\/ef49a1871aa7378da9d8d3cd2875d9b3"},"headline":"March\u00e9 mondial : la fraise par FreshPlaza","datePublished":"2026-04-13T14:18:21+00:00","dateModified":"2026-04-13T14:18:22+00:00","mainEntityOfPage":{"@id":"https:\/\/befve.com\/en\/marche-mondial-la-fraise-par-freshplaza\/"},"wordCount":2661,"publisher":{"@id":"https:\/\/befve.com\/en\/#organization"},"image":{"@id":"https:\/\/befve.com\/en\/marche-mondial-la-fraise-par-freshplaza\/#primaryimage"},"thumbnailUrl":"https:\/\/befve.com\/wp-content\/uploads\/2026\/05\/articles-Christian-Befve-scaled.jpg","articleSection":["Non cat\u00e9goris\u00e9"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/befve.com\/en\/marche-mondial-la-fraise-par-freshplaza\/","url":"https:\/\/befve.com\/en\/marche-mondial-la-fraise-par-freshplaza\/","name":"March\u00e9 mondial : la fraise par FreshPlaza - Befve &amp; Co","isPartOf":{"@id":"https:\/\/befve.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/befve.com\/en\/marche-mondial-la-fraise-par-freshplaza\/#primaryimage"},"image":{"@id":"https:\/\/befve.com\/en\/marche-mondial-la-fraise-par-freshplaza\/#primaryimage"},"thumbnailUrl":"https:\/\/befve.com\/wp-content\/uploads\/2026\/05\/articles-Christian-Befve-scaled.jpg","datePublished":"2026-04-13T14:18:21+00:00","dateModified":"2026-04-13T14:18:22+00:00","breadcrumb":{"@id":"https:\/\/befve.com\/en\/marche-mondial-la-fraise-par-freshplaza\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/befve.com\/en\/marche-mondial-la-fraise-par-freshplaza\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/befve.com\/en\/marche-mondial-la-fraise-par-freshplaza\/#primaryimage","url":"https:\/\/befve.com\/wp-content\/uploads\/2026\/05\/articles-Christian-Befve-scaled.jpg","contentUrl":"https:\/\/befve.com\/wp-content\/uploads\/2026\/05\/articles-Christian-Befve-scaled.jpg","width":2560,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/befve.com\/en\/marche-mondial-la-fraise-par-freshplaza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/befve.com\/en\/"},{"@type":"ListItem","position":2,"name":"March\u00e9 mondial : la fraise par FreshPlaza"}]},{"@type":"WebSite","@id":"https:\/\/befve.com\/en\/#website","url":"https:\/\/befve.com\/en\/","name":"Befve &Co","description":"Christian Befve expert &amp; consultant asperges","publisher":{"@id":"https:\/\/befve.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/befve.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/befve.com\/en\/#organization","name":"Befve &Co","alternateName":"Befve &Co","url":"https:\/\/befve.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/befve.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/befve.com\/wp-content\/uploads\/logo_green.svg","contentUrl":"https:\/\/befve.com\/wp-content\/uploads\/logo_green.svg","caption":"Befve &Co"},"image":{"@id":"https:\/\/befve.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/befve.com\/en\/#\/schema\/person\/ef49a1871aa7378da9d8d3cd2875d9b3","name":"Christian","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g","caption":"Christian"},"url":"https:\/\/befve.com\/en\/author\/christian\/"}]}},"_links":{"self":[{"href":"https:\/\/befve.com\/en\/wp-json\/wp\/v2\/posts\/265883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/befve.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/befve.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/befve.com\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/befve.com\/en\/wp-json\/wp\/v2\/comments?post=265883"}],"version-history":[{"count":1,"href":"https:\/\/befve.com\/en\/wp-json\/wp\/v2\/posts\/265883\/revisions"}],"predecessor-version":[{"id":265885,"href":"https:\/\/befve.com\/en\/wp-json\/wp\/v2\/posts\/265883\/revisions\/265885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/befve.com\/en\/wp-json\/wp\/v2\/media\/266085"}],"wp:attachment":[{"href":"https:\/\/befve.com\/en\/wp-json\/wp\/v2\/media?parent=265883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/befve.com\/en\/wp-json\/wp\/v2\/categories?post=265883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/befve.com\/en\/wp-json\/wp\/v2\/tags?post=265883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}