{"id":24546,"date":"2024-11-05T16:03:20","date_gmt":"2024-11-05T15:03:20","guid":{"rendered":"https:\/\/befve.com\/?p=24546"},"modified":"2024-11-05T16:03:20","modified_gmt":"2024-11-05T15:03:20","slug":"les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte","status":"publish","type":"post","link":"https:\/\/befve.com\/es\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\/","title":{"rendered":"Les asperges : super &#8211; l\u00e9gumes &#8211; YouTube Les asperges ses b\u00e9n\u00e9fices et bienfaits: pauvre en calories, ce l\u00e9gume de printemps contient des antioxydants (les anthocyanes qui lui donnent sa couleur verte ou violac\u00e9e) &#8230;"},"content":{"rendered":"<p><a href=\"https:\/\/www.youtube.com\/watch?v=UbRKOnSRIHs\">https:\/\/www.youtube.com\/watch?v=UbRKOnSRIHs<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":37267,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":4,"footnotes":""},"categories":[52],"tags":[],"class_list":["post-24546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recettes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les asperges : super - l\u00e9gumes - YouTube Les asperges ses b\u00e9n\u00e9fices et bienfaits: pauvre en calories, ce l\u00e9gume de printemps contient des antioxydants (les anthocyanes qui lui donnent sa couleur verte ou violac\u00e9e) ... - Befve &amp; Co<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/befve.com\/es\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les asperges : super - l\u00e9gumes - YouTube Les asperges ses b\u00e9n\u00e9fices et bienfaits: pauvre en calories, ce l\u00e9gume de printemps contient des antioxydants (les anthocyanes qui lui donnent sa couleur verte ou violac\u00e9e) ... - Befve &amp; Co\" \/>\n<meta property=\"og:url\" content=\"https:\/\/befve.com\/es\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\/\" \/>\n<meta property=\"og:site_name\" content=\"Befve &amp; Co\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-05T15:03:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2444\" \/>\n\t<meta property=\"og:image:height\" content=\"1020\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\\\/\"},\"author\":{\"name\":\"Lola\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#\\\/schema\\\/person\\\/4ee575776823d7040f65f14cc647850f\"},\"headline\":\"Les asperges : super &#8211; l\u00e9gumes &#8211; YouTube Les asperges ses b\u00e9n\u00e9fices et bienfaits: pauvre en calories, ce l\u00e9gume de printemps contient des antioxydants (les anthocyanes qui lui donnent sa couleur verte ou violac\u00e9e) &#8230;\",\"datePublished\":\"2024-11-05T15:03:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\\\/\"},\"wordCount\":47,\"publisher\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/articles-1.jpg\",\"articleSection\":[\"Recettes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\\\/\",\"url\":\"https:\\\/\\\/befve.com\\\/es\\\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\\\/\",\"name\":\"Les asperges : super - l\u00e9gumes - YouTube Les asperges ses b\u00e9n\u00e9fices et bienfaits: pauvre en calories, ce l\u00e9gume de printemps contient des antioxydants (les anthocyanes qui lui donnent sa couleur verte ou violac\u00e9e) ... - Befve &amp; Co\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/articles-1.jpg\",\"datePublished\":\"2024-11-05T15:03:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/befve.com\\\/es\\\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/articles-1.jpg\",\"contentUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/articles-1.jpg\",\"width\":2444,\"height\":1020,\"caption\":\"befve asperges\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/befve.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les asperges : super &#8211; l\u00e9gumes &#8211; YouTube Les asperges ses b\u00e9n\u00e9fices et bienfaits: pauvre en calories, ce l\u00e9gume de printemps contient des antioxydants (les anthocyanes qui lui donnent sa couleur verte ou violac\u00e9e) &#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/befve.com\\\/es\\\/\",\"name\":\"Befve &Co\",\"description\":\"Christian Befve expert &amp; consultant asperges\",\"publisher\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/befve.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#organization\",\"name\":\"Befve &Co\",\"alternateName\":\"Befve &Co\",\"url\":\"https:\\\/\\\/befve.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/logo_green.svg\",\"contentUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/logo_green.svg\",\"caption\":\"Befve &Co\"},\"image\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#\\\/schema\\\/person\\\/4ee575776823d7040f65f14cc647850f\",\"name\":\"Lola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2241487f462784423897bf42e4849904248a85d18d6f8c30d9f6414c4dada9a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2241487f462784423897bf42e4849904248a85d18d6f8c30d9f6414c4dada9a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2241487f462784423897bf42e4849904248a85d18d6f8c30d9f6414c4dada9a7?s=96&d=mm&r=g\",\"caption\":\"Lola\"},\"url\":\"https:\\\/\\\/befve.com\\\/es\\\/author\\\/lola\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les asperges : super - l\u00e9gumes - YouTube Les asperges ses b\u00e9n\u00e9fices et bienfaits: pauvre en calories, ce l\u00e9gume de printemps contient des antioxydants (les anthocyanes qui lui donnent sa couleur verte ou violac\u00e9e) ... - Befve &amp; Co","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/befve.com\/es\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\/","og_locale":"es_ES","og_type":"article","og_title":"Les asperges : super - l\u00e9gumes - YouTube Les asperges ses b\u00e9n\u00e9fices et bienfaits: pauvre en calories, ce l\u00e9gume de printemps contient des antioxydants (les anthocyanes qui lui donnent sa couleur verte ou violac\u00e9e) ... - Befve &amp; Co","og_url":"https:\/\/befve.com\/es\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\/","og_site_name":"Befve &amp; Co","article_published_time":"2024-11-05T15:03:20+00:00","og_image":[{"width":2444,"height":1020,"url":"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg","type":"image\/jpeg"}],"author":"Lola","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lola","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/befve.com\/es\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\/#article","isPartOf":{"@id":"https:\/\/befve.com\/es\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\/"},"author":{"name":"Lola","@id":"https:\/\/befve.com\/es\/#\/schema\/person\/4ee575776823d7040f65f14cc647850f"},"headline":"Les asperges : super &#8211; l\u00e9gumes &#8211; YouTube Les asperges ses b\u00e9n\u00e9fices et bienfaits: pauvre en calories, ce l\u00e9gume de printemps contient des antioxydants (les anthocyanes qui lui donnent sa couleur verte ou violac\u00e9e) &#8230;","datePublished":"2024-11-05T15:03:20+00:00","mainEntityOfPage":{"@id":"https:\/\/befve.com\/es\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\/"},"wordCount":47,"publisher":{"@id":"https:\/\/befve.com\/es\/#organization"},"image":{"@id":"https:\/\/befve.com\/es\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\/#primaryimage"},"thumbnailUrl":"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg","articleSection":["Recettes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/befve.com\/es\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\/","url":"https:\/\/befve.com\/es\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\/","name":"Les asperges : super - l\u00e9gumes - YouTube Les asperges ses b\u00e9n\u00e9fices et bienfaits: pauvre en calories, ce l\u00e9gume de printemps contient des antioxydants (les anthocyanes qui lui donnent sa couleur verte ou violac\u00e9e) ... - Befve &amp; Co","isPartOf":{"@id":"https:\/\/befve.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/befve.com\/es\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\/#primaryimage"},"image":{"@id":"https:\/\/befve.com\/es\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\/#primaryimage"},"thumbnailUrl":"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg","datePublished":"2024-11-05T15:03:20+00:00","breadcrumb":{"@id":"https:\/\/befve.com\/es\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/befve.com\/es\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/befve.com\/es\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\/#primaryimage","url":"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg","contentUrl":"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg","width":2444,"height":1020,"caption":"befve asperges"},{"@type":"BreadcrumbList","@id":"https:\/\/befve.com\/es\/les-asperges-super-legumes-youtube-les-asperges-ses-benefices-et-bienfaits-pauvre-en-calories-ce-legume-de-printemps-contient-des-antioxydants-les-anthocyanes-qui-lui-donnent-sa-couleur-verte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/befve.com\/es\/"},{"@type":"ListItem","position":2,"name":"Les asperges : super &#8211; l\u00e9gumes &#8211; YouTube Les asperges ses b\u00e9n\u00e9fices et bienfaits: pauvre en calories, ce l\u00e9gume de printemps contient des antioxydants (les anthocyanes qui lui donnent sa couleur verte ou violac\u00e9e) &#8230;"}]},{"@type":"WebSite","@id":"https:\/\/befve.com\/es\/#website","url":"https:\/\/befve.com\/es\/","name":"Befve &Co","description":"Christian Befve expert &amp; consultant asperges","publisher":{"@id":"https:\/\/befve.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/befve.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/befve.com\/es\/#organization","name":"Befve &Co","alternateName":"Befve &Co","url":"https:\/\/befve.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/befve.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/befve.com\/wp-content\/uploads\/logo_green.svg","contentUrl":"https:\/\/befve.com\/wp-content\/uploads\/logo_green.svg","caption":"Befve &Co"},"image":{"@id":"https:\/\/befve.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/befve.com\/es\/#\/schema\/person\/4ee575776823d7040f65f14cc647850f","name":"Lola","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2241487f462784423897bf42e4849904248a85d18d6f8c30d9f6414c4dada9a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2241487f462784423897bf42e4849904248a85d18d6f8c30d9f6414c4dada9a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2241487f462784423897bf42e4849904248a85d18d6f8c30d9f6414c4dada9a7?s=96&d=mm&r=g","caption":"Lola"},"url":"https:\/\/befve.com\/es\/author\/lola\/"}]}},"_links":{"self":[{"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/posts\/24546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/comments?post=24546"}],"version-history":[{"count":0,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/posts\/24546\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/media\/37267"}],"wp:attachment":[{"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/media?parent=24546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/categories?post=24546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/tags?post=24546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}