{"id":265734,"date":"2026-03-27T14:58:34","date_gmt":"2026-03-27T14:58:34","guid":{"rendered":"https:\/\/befve.com\/?p=265734"},"modified":"2026-03-27T14:58:35","modified_gmt":"2026-03-27T14:58:35","slug":"se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza","status":"publish","type":"post","link":"https:\/\/befve.com\/es\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\/","title":{"rendered":"Se espera un repunte de la cosecha de fresas de California por la ola de calor por G.W. Palmer &amp; Co., Inc. y FreshPlaza"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">Se espera un repunte de la cosecha de fresas de California por la ola de calor<\/h1>\n\n\n\n<p>Aunque la semana pasada el sur de California fue testigo de una ola de calor sin precedentes, es probable que la cosecha de fresas de primavera de Salinas-Watsonville, en especial, se vea recompensada. \u00abTodo este calor causar\u00e1 un peque\u00f1o par\u00f3n en la oferta porque se descartar\u00e1 algo de fruta blanda o quemada por el sol. Sin embargo, a largo plazo, para abril se espera una cosecha muy buena\u00bb, dice Steve Johnston, de G.W. Palmer &amp; Co. Inc.<\/p>\n\n\n\n<p>Eso significa que, aunque las fresas empezaron a salir pronto este a\u00f1o en la regi\u00f3n \u2014a principios de febrero ya se vieron algunos vol\u00famenes\u2014, con el tir\u00f3n de la Semana Santa a unos 10 d\u00edas vista, se esperan buenas cantidades para la festividad. \u00abAbril va a tener mucha producci\u00f3n porque las temperaturas del suelo se est\u00e1n incrementando\u00bb, seg\u00fan Johnston, que se\u00f1ala que, adem\u00e1s de Salinas-Watsonville, tambi\u00e9n est\u00e1n ya en producci\u00f3n Santa Mar\u00eda, Oxnard y Baja California.<\/p>\n\n\n\n<p>Todo ello tras un invierno m\u00e1s c\u00e1lido de lo normal en California y lluvias regulares. \u00abHace probablemente un mes cayeron unas muy buenas lluvias, pero desde entonces, nada. El a\u00f1o pasado tuvimos una buena temporada de lluvias, y este a\u00f1o ha sido intermitente, as\u00ed que deber\u00edamos tener mejor volumen en Salinas-Watsonville en comparaci\u00f3n con el a\u00f1o pasado\u00bb, explica Johnston.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.freshplaza.es\/remote\/https\/agfstorage.blob.core.windows.net\/misc\/FP_com\/2026\/03\/19\/Palmerstrawberriesedited.jpg?preset=ContentFullSmall\" alt=\"\"\/><\/figure>\n\n\n\n<p><strong>Queda atr\u00e1s la temporada de lluvias<\/strong><br>Con la temporada de lluvias de octubre-marzo en California pr\u00e1cticamente superada, y sin lluvias en el horizonte en un futuro pr\u00f3ximo, la producci\u00f3n tambi\u00e9n se ver\u00e1 favorecida. \u00abTambi\u00e9n hemos tenido muy pocas heladas matutinas. Nunca hab\u00eda visto una racha as\u00ed en todos mis a\u00f1os en Salinas\u00bb, dice Johnston.<\/p>\n\n\n\n<p>Con este sorprendente calor, se prev\u00e9 que las instalaciones de refrigeraci\u00f3n tambi\u00e9n empiecen a encenderse esta semana o la pr\u00f3xima para proteger la fruta, sobre todo teniendo en cuenta que el tr\u00e1fico de camiones en la regi\u00f3n sigue siendo escaso, con cargas mixtas de hortalizas que acaban de empezar a embarcarse.<\/p>\n\n\n\n<p>Para colocar una cosecha que se prev\u00e9 abundante, tambi\u00e9n ser\u00e1 necesario el apoyo del <em>retail<\/em>. \u00abEste a\u00f1o tendremos unas fresas preciosas, pero hay que comercializarlas bien, porque habr\u00e1 muchas\u00bb, afirma Johnston. \u00abLos <em>retailers<\/em> tienen que poner buenas promociones. El dinero escasea, y las fresas son un lujo, as\u00ed que m\u00e1s vale que no las vendan a 5,99 $, por ejemplo\u00bb.<\/p>\n\n\n\n<p><img decoding=\"async\" src=\"https:\/\/www.freshplaza.es\/remote\/https\/agfstorage.blob.core.windows.net\/misc\/FP_com\/2026\/03\/19\/GWPalmerlogoedited.jpg?preset=ContentCustom\" alt=\"\" class=\"\">Para m\u00e1s informaci\u00f3n:<br>Steve Johnston<br><strong>G.W. Palmer &amp; Co., Inc.<br><\/strong>Tel.: +1 (831) 753-6578<br><a href=\"mailto:sjohnston@gwpalmer.net?subject=Response to FreshPlaza.com article\" target=\"_blank\" rel=\"noreferrer noopener\">sjohnston@gwpalmer.net<\/a><br><a href=\"http:\/\/www.gwpalmer.net\/\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.gwpalmer.net\/<\/a> Fecha de publicaci\u00f3n: vie. 27 mar. 2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se espera un repunte de la cosecha de fresas de California por la ola de calor Aunque la semana pasada el sur de California fue testigo de una ola de calor sin precedentes, es probable que la cosecha de fresas de primavera de Salinas-Watsonville, en especial, se vea recompensada. \u00abTodo este calor causar\u00e1 un peque\u00f1o [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":37267,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":0,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-265734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se espera un repunte de la cosecha de fresas de California por la ola de calor por G.W. Palmer &amp; Co., Inc. y FreshPlaza - Befve &amp; Co<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/befve.com\/es\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se espera un repunte de la cosecha de fresas de California por la ola de calor por G.W. Palmer &amp; Co., Inc. y FreshPlaza - Befve &amp; Co\" \/>\n<meta property=\"og:description\" content=\"Se espera un repunte de la cosecha de fresas de California por la ola de calor Aunque la semana pasada el sur de California fue testigo de una ola de calor sin precedentes, es probable que la cosecha de fresas de primavera de Salinas-Watsonville, en especial, se vea recompensada. \u00abTodo este calor causar\u00e1 un peque\u00f1o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/befve.com\/es\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\/\" \/>\n<meta property=\"og:site_name\" content=\"Befve &amp; Co\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-27T14:58:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-27T14:58:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2444\" \/>\n\t<meta property=\"og:image:height\" content=\"1020\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\\\/\"},\"author\":{\"name\":\"Christian\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#\\\/schema\\\/person\\\/ef49a1871aa7378da9d8d3cd2875d9b3\"},\"headline\":\"Se espera un repunte de la cosecha de fresas de California por la ola de calor por G.W. Palmer &amp; Co., Inc. y FreshPlaza\",\"datePublished\":\"2026-03-27T14:58:34+00:00\",\"dateModified\":\"2026-03-27T14:58:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\\\/\"},\"wordCount\":483,\"publisher\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/articles-1.jpg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\\\/\",\"url\":\"https:\\\/\\\/befve.com\\\/es\\\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\\\/\",\"name\":\"Se espera un repunte de la cosecha de fresas de California por la ola de calor por G.W. Palmer &amp; Co., Inc. y FreshPlaza - Befve &amp; Co\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/articles-1.jpg\",\"datePublished\":\"2026-03-27T14:58:34+00:00\",\"dateModified\":\"2026-03-27T14:58:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/befve.com\\\/es\\\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/articles-1.jpg\",\"contentUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/articles-1.jpg\",\"width\":2444,\"height\":1020,\"caption\":\"befve asperges\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/befve.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se espera un repunte de la cosecha de fresas de California por la ola de calor por G.W. Palmer &amp; Co., Inc. y FreshPlaza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/befve.com\\\/es\\\/\",\"name\":\"Befve &Co\",\"description\":\"Christian Befve expert &amp; consultant asperges\",\"publisher\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/befve.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#organization\",\"name\":\"Befve &Co\",\"alternateName\":\"Befve &Co\",\"url\":\"https:\\\/\\\/befve.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/logo_green.svg\",\"contentUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/logo_green.svg\",\"caption\":\"Befve &Co\"},\"image\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#\\\/schema\\\/person\\\/ef49a1871aa7378da9d8d3cd2875d9b3\",\"name\":\"Christian\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g\",\"caption\":\"Christian\"},\"url\":\"https:\\\/\\\/befve.com\\\/es\\\/author\\\/christian\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se espera un repunte de la cosecha de fresas de California por la ola de calor por G.W. Palmer &amp; Co., Inc. y FreshPlaza - Befve &amp; Co","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/befve.com\/es\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\/","og_locale":"es_ES","og_type":"article","og_title":"Se espera un repunte de la cosecha de fresas de California por la ola de calor por G.W. Palmer &amp; Co., Inc. y FreshPlaza - Befve &amp; Co","og_description":"Se espera un repunte de la cosecha de fresas de California por la ola de calor Aunque la semana pasada el sur de California fue testigo de una ola de calor sin precedentes, es probable que la cosecha de fresas de primavera de Salinas-Watsonville, en especial, se vea recompensada. \u00abTodo este calor causar\u00e1 un peque\u00f1o [&hellip;]","og_url":"https:\/\/befve.com\/es\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\/","og_site_name":"Befve &amp; Co","article_published_time":"2026-03-27T14:58:34+00:00","article_modified_time":"2026-03-27T14:58:35+00:00","og_image":[{"width":2444,"height":1020,"url":"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg","type":"image\/jpeg"}],"author":"Christian","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Christian","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/befve.com\/es\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\/#article","isPartOf":{"@id":"https:\/\/befve.com\/es\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\/"},"author":{"name":"Christian","@id":"https:\/\/befve.com\/es\/#\/schema\/person\/ef49a1871aa7378da9d8d3cd2875d9b3"},"headline":"Se espera un repunte de la cosecha de fresas de California por la ola de calor por G.W. Palmer &amp; Co., Inc. y FreshPlaza","datePublished":"2026-03-27T14:58:34+00:00","dateModified":"2026-03-27T14:58:35+00:00","mainEntityOfPage":{"@id":"https:\/\/befve.com\/es\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\/"},"wordCount":483,"publisher":{"@id":"https:\/\/befve.com\/es\/#organization"},"image":{"@id":"https:\/\/befve.com\/es\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\/#primaryimage"},"thumbnailUrl":"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/befve.com\/es\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\/","url":"https:\/\/befve.com\/es\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\/","name":"Se espera un repunte de la cosecha de fresas de California por la ola de calor por G.W. Palmer &amp; Co., Inc. y FreshPlaza - Befve &amp; Co","isPartOf":{"@id":"https:\/\/befve.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/befve.com\/es\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\/#primaryimage"},"image":{"@id":"https:\/\/befve.com\/es\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\/#primaryimage"},"thumbnailUrl":"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg","datePublished":"2026-03-27T14:58:34+00:00","dateModified":"2026-03-27T14:58:35+00:00","breadcrumb":{"@id":"https:\/\/befve.com\/es\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/befve.com\/es\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/befve.com\/es\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\/#primaryimage","url":"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg","contentUrl":"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg","width":2444,"height":1020,"caption":"befve asperges"},{"@type":"BreadcrumbList","@id":"https:\/\/befve.com\/es\/se-espera-un-repunte-de-la-cosecha-de-fresas-de-california-por-la-ola-de-calor-por-g-w-palmer-co-inc-y-freshplaza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/befve.com\/es\/"},{"@type":"ListItem","position":2,"name":"Se espera un repunte de la cosecha de fresas de California por la ola de calor por G.W. Palmer &amp; Co., Inc. y FreshPlaza"}]},{"@type":"WebSite","@id":"https:\/\/befve.com\/es\/#website","url":"https:\/\/befve.com\/es\/","name":"Befve &Co","description":"Christian Befve expert &amp; consultant asperges","publisher":{"@id":"https:\/\/befve.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/befve.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/befve.com\/es\/#organization","name":"Befve &Co","alternateName":"Befve &Co","url":"https:\/\/befve.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/befve.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/befve.com\/wp-content\/uploads\/logo_green.svg","contentUrl":"https:\/\/befve.com\/wp-content\/uploads\/logo_green.svg","caption":"Befve &Co"},"image":{"@id":"https:\/\/befve.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/befve.com\/es\/#\/schema\/person\/ef49a1871aa7378da9d8d3cd2875d9b3","name":"Christian","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g","caption":"Christian"},"url":"https:\/\/befve.com\/es\/author\/christian\/"}]}},"_links":{"self":[{"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/posts\/265734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/comments?post=265734"}],"version-history":[{"count":1,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/posts\/265734\/revisions"}],"predecessor-version":[{"id":265735,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/posts\/265734\/revisions\/265735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/media\/37267"}],"wp:attachment":[{"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/media?parent=265734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/categories?post=265734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/tags?post=265734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}