{"id":266767,"date":"2026-06-25T12:55:10","date_gmt":"2026-06-25T12:55:10","guid":{"rendered":"https:\/\/befve.com\/?p=266767"},"modified":"2026-06-25T12:55:11","modified_gmt":"2026-06-25T12:55:11","slug":"nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza","status":"publish","type":"post","link":"https:\/\/befve.com\/es\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\/","title":{"rendered":"\u00ab Nous tablons sur des recettes nettes sup\u00e9rieures \u00e0 celles de l\u2019ann\u00e9e derni\u00e8re \u00bb par Exploitation fruiti\u00e8re Kn\u00f6bl et FreshPlaza"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">D\u00e9but de la r\u00e9colte des groseilles pr\u00e9coces dans le sud du Burgenland :<\/p>\n\n\n\n<h1 class=\"wp-block-heading\"><strong>Exploitation fruiti\u00e8re Kn\u00f6bl<\/strong><\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">Comme les ann\u00e9es pr\u00e9c\u00e9dentes, la r\u00e9colte des groseilles dans le sud du Burgenland a d\u00e9but\u00e9 au cours de la semaine 24. \u00ab Apr\u00e8s un mois de mars et un mois d&#8217;avril particuli\u00e8rement secs, le mois de mai a \u00e9t\u00e9 chaud et relativement bien arros\u00e9. Sans irrigation, nous aurions toutefois enregistr\u00e9 des pertes consid\u00e9rables, car la vari\u00e9t\u00e9 Marlena, que nous cultivons exclusivement, fleurit pr\u00e9cis\u00e9ment \u00e0 cette p\u00e9riode, en mars \u00bb, explique David Kn\u00f6bl, de l&#8217;exploitation fruiti\u00e8re \u00e9ponyme situ\u00e9e \u00e0 Neudauberg, dans le sud du Burgenland.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En plus de la production de pommes, M. Kn\u00f6bl cultive depuis maintenant cinq ans des groseilles pr\u00e9coces sur une surface d&#8217;environ 1,3 hectare. Les fruits sont commercialis\u00e9s exclusivement aupr\u00e8s du commerce de d\u00e9tail alimentaire r\u00e9gional par l&#8217;interm\u00e9diaire de son partenaire styrien Lammer Fruchtlogistik GmbH. La r\u00e9colte s&#8217;\u00e9tale sur les semaines 24 et 25, avant que l&#8217;int\u00e9gralit\u00e9 des volumes r\u00e9colt\u00e9s ne soit \u00e9coul\u00e9e en moins de deux semaines. \u00ab Nous pr\u00e9voyons un volume total d&#8217;environ 15 \u00e0 16 tonnes, soit un niveau comparable \u00e0 celui de l&#8217;ann\u00e9e derni\u00e8re. Toutefois, la r\u00e9colte pr\u00e9c\u00e9dente comptait proportionnellement davantage de petits fruits, principalement en raison de la pr\u00e9sence de bois de deux ans. Cette ann\u00e9e, nous avons presque exclusivement du bois d&#8217;un an, ce qui devrait se traduire par des fruits plus gros, de meilleurs rendements et, par cons\u00e9quent, des recettes nettes plus \u00e9lev\u00e9es. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>La vari\u00e9t\u00e9 pr\u00e9coce Marlena permet une commercialisation anticip\u00e9e des groseilles produites localement. Elle arrive \u00e0 maturit\u00e9 nettement plus t\u00f4t que les vari\u00e9t\u00e9s traditionnellement cultiv\u00e9es en Autriche, comme Haronia et Rovada<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le producteur reste encore prudent concernant les perspectives commerciales pr\u00e9cises. \u00ab Il faut toutefois tenir compte du fait que la demande pourrait \u00eatre l\u00e9g\u00e8rement inf\u00e9rieure cette ann\u00e9e en raison de la prudence persistante des consommateurs en mati\u00e8re d&#8217;achats \u00bb, explique M. Kn\u00f6bl. Les prix devraient n\u00e9anmoins rester globalement comparables \u00e0 ceux de l&#8217;ann\u00e9e derni\u00e8re. En magasin, les groseilles issues de la production locale sont propos\u00e9es soit en barquettes de 250 g (groupe Rewe), soit en barquettes de 500 g (Hofer).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un enrichissement de l&#8217;assortiment<\/strong><br>Cinq ans apr\u00e8s la premi\u00e8re r\u00e9colte, l&#8217;exploitation fruiti\u00e8re familiale tire un bilan particuli\u00e8rement positif de cette production. \u00ab Gr\u00e2ce \u00e0 cette entr\u00e9e en saison pr\u00e9coce, notre partenaire commercial consolide sa pr\u00e9sence sur le march\u00e9 et compl\u00e8te son assortiment existant, principalement bas\u00e9 sur les vari\u00e9t\u00e9s Haronia et Rovada. Pour nous, en tant que producteurs, la groseille repr\u00e9sente d\u00e9sormais une v\u00e9ritable gamme \u00e0 part enti\u00e8re qui, notamment gr\u00e2ce \u00e0 son calendrier de r\u00e9colte, s&#8217;int\u00e8gre parfaitement \u00e0 c\u00f4t\u00e9 de la culture des pommes. \u00bb En p\u00e9riode de pointe, l&#8217;exploitation emploie jusqu&#8217;\u00e0 18 cueilleurs, principalement originaires d&#8217;Ukraine.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.freshplaza.fr\/remote\/https\/agfstorage.blob.core.windows.net\/misc\/FP_de\/2026\/06\/16\/knoebl.jpg?preset=ContentFullSmall\" alt=\"\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La Pinova poursuit son d\u00e9veloppement<\/strong><br>Le verger de pommiers de l&#8217;exploitation comprend un large \u00e9ventail de vari\u00e9t\u00e9s, parmi lesquelles Golden Delicious, Pinova, Supernova (un mutant de Pinova), Granny Smith, Idared, Braeburn et Fuji. La surface totale cultiv\u00e9e atteint environ 16 hectares. \u00ab Nous devrions tr\u00e8s probablement enregistrer une r\u00e9colte moyenne cette ann\u00e9e. En raison du mois de mai chaud et humide qui a suivi directement la floraison, nous aurons probablement une proportion l\u00e9g\u00e8rement plus \u00e9lev\u00e9e de fruits tomb\u00e9s, comme cela a \u00e9galement \u00e9t\u00e9 le cas pour les groseilles. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 l&#8217;exception de quelques pertes limit\u00e9es dans les zones situ\u00e9es en altitude, l&#8217;exploitation a \u00e9t\u00e9 largement \u00e9pargn\u00e9e par les d\u00e9g\u00e2ts li\u00e9s au gel. La r\u00e9colte des pommes commence g\u00e9n\u00e9ralement \u00e0 partir de la mi-septembre, apr\u00e8s quoi les fruits sont commercialis\u00e9s exclusivement sur le march\u00e9 libre. \u00ab Ces derni\u00e8res ann\u00e9es, nous avons ajust\u00e9 nos surfaces par vari\u00e9t\u00e9 en fonction de l&#8217;\u00e9volution de la demande. Nous avons ainsi progressivement augment\u00e9 les volumes de Pinova, tandis que nous avons l\u00e9g\u00e8rement r\u00e9duit ceux de Fuji. Dans les prochaines ann\u00e9es, nous poursuivrons cette orientation et remplacerons progressivement les vari\u00e9t\u00e9s plus anciennes, comme l&#8217;Idared, par la Pinova \u00bb, conclut-il.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour plus d&#8217;informations :<br>David Kn\u00f6bl<br><strong>Exploitation fruiti\u00e8re Kn\u00f6bl<\/strong><br>Gemeindestra\u00dfe 9<br>7574 Neudauberg<br>T\u00e9l. : +43 664 8685730<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9but de la r\u00e9colte des groseilles pr\u00e9coces dans le sud du Burgenland : Exploitation fruiti\u00e8re Kn\u00f6bl Comme les ann\u00e9es pr\u00e9c\u00e9dentes, la r\u00e9colte des groseilles dans le sud du Burgenland a d\u00e9but\u00e9 au cours de la semaine 24. \u00ab Apr\u00e8s un mois de mars et un mois d&#8217;avril particuli\u00e8rement secs, le mois de mai a \u00e9t\u00e9 [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":266085,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":4,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-266767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorise"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00ab Nous tablons sur des recettes nettes sup\u00e9rieures \u00e0 celles de l\u2019ann\u00e9e derni\u00e8re \u00bb par Exploitation fruiti\u00e8re Kn\u00f6bl et FreshPlaza - Befve &amp; Co<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/befve.com\/es\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00ab Nous tablons sur des recettes nettes sup\u00e9rieures \u00e0 celles de l\u2019ann\u00e9e derni\u00e8re \u00bb par Exploitation fruiti\u00e8re Kn\u00f6bl et FreshPlaza - Befve &amp; Co\" \/>\n<meta property=\"og:description\" content=\"D\u00e9but de la r\u00e9colte des groseilles pr\u00e9coces dans le sud du Burgenland : Exploitation fruiti\u00e8re Kn\u00f6bl Comme les ann\u00e9es pr\u00e9c\u00e9dentes, la r\u00e9colte des groseilles dans le sud du Burgenland a d\u00e9but\u00e9 au cours de la semaine 24. \u00ab Apr\u00e8s un mois de mars et un mois d&#8217;avril particuli\u00e8rement secs, le mois de mai a \u00e9t\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/befve.com\/es\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\/\" \/>\n<meta property=\"og:site_name\" content=\"Befve &amp; Co\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-25T12:55:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-25T12:55:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/befve.com\/wp-content\/uploads\/2026\/05\/articles-Christian-Befve-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\\\/\"},\"author\":{\"name\":\"Christian\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#\\\/schema\\\/person\\\/ef49a1871aa7378da9d8d3cd2875d9b3\"},\"headline\":\"\u00ab Nous tablons sur des recettes nettes sup\u00e9rieures \u00e0 celles de l\u2019ann\u00e9e derni\u00e8re \u00bb par Exploitation fruiti\u00e8re Kn\u00f6bl et FreshPlaza\",\"datePublished\":\"2026-06-25T12:55:10+00:00\",\"dateModified\":\"2026-06-25T12:55:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\\\/\"},\"wordCount\":776,\"publisher\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/articles-Christian-Befve-scaled.jpg\",\"articleSection\":[\"Non cat\u00e9goris\u00e9\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\\\/\",\"url\":\"https:\\\/\\\/befve.com\\\/es\\\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\\\/\",\"name\":\"\u00ab Nous tablons sur des recettes nettes sup\u00e9rieures \u00e0 celles de l\u2019ann\u00e9e derni\u00e8re \u00bb par Exploitation fruiti\u00e8re Kn\u00f6bl et FreshPlaza - Befve &amp; Co\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/articles-Christian-Befve-scaled.jpg\",\"datePublished\":\"2026-06-25T12:55:10+00:00\",\"dateModified\":\"2026-06-25T12:55:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/befve.com\\\/es\\\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/articles-Christian-Befve-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/articles-Christian-Befve-scaled.jpg\",\"width\":2560,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/befve.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab Nous tablons sur des recettes nettes sup\u00e9rieures \u00e0 celles de l\u2019ann\u00e9e derni\u00e8re \u00bb par Exploitation fruiti\u00e8re Kn\u00f6bl et FreshPlaza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/befve.com\\\/es\\\/\",\"name\":\"Befve &Co\",\"description\":\"Christian Befve expert &amp; consultant asperges\",\"publisher\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/befve.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#organization\",\"name\":\"Befve &Co\",\"alternateName\":\"Befve &Co\",\"url\":\"https:\\\/\\\/befve.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/logo_green.svg\",\"contentUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/logo_green.svg\",\"caption\":\"Befve &Co\"},\"image\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#\\\/schema\\\/person\\\/ef49a1871aa7378da9d8d3cd2875d9b3\",\"name\":\"Christian\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g\",\"caption\":\"Christian\"},\"url\":\"https:\\\/\\\/befve.com\\\/es\\\/author\\\/christian\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00ab Nous tablons sur des recettes nettes sup\u00e9rieures \u00e0 celles de l\u2019ann\u00e9e derni\u00e8re \u00bb par Exploitation fruiti\u00e8re Kn\u00f6bl et FreshPlaza - Befve &amp; Co","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/befve.com\/es\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\/","og_locale":"es_ES","og_type":"article","og_title":"\u00ab Nous tablons sur des recettes nettes sup\u00e9rieures \u00e0 celles de l\u2019ann\u00e9e derni\u00e8re \u00bb par Exploitation fruiti\u00e8re Kn\u00f6bl et FreshPlaza - Befve &amp; Co","og_description":"D\u00e9but de la r\u00e9colte des groseilles pr\u00e9coces dans le sud du Burgenland : Exploitation fruiti\u00e8re Kn\u00f6bl Comme les ann\u00e9es pr\u00e9c\u00e9dentes, la r\u00e9colte des groseilles dans le sud du Burgenland a d\u00e9but\u00e9 au cours de la semaine 24. \u00ab Apr\u00e8s un mois de mars et un mois d&#8217;avril particuli\u00e8rement secs, le mois de mai a \u00e9t\u00e9 [&hellip;]","og_url":"https:\/\/befve.com\/es\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\/","og_site_name":"Befve &amp; Co","article_published_time":"2026-06-25T12:55:10+00:00","article_modified_time":"2026-06-25T12:55:11+00:00","og_image":[{"width":2560,"height":512,"url":"https:\/\/befve.com\/wp-content\/uploads\/2026\/05\/articles-Christian-Befve-scaled.jpg","type":"image\/jpeg"}],"author":"Christian","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Christian","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/befve.com\/es\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\/#article","isPartOf":{"@id":"https:\/\/befve.com\/es\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\/"},"author":{"name":"Christian","@id":"https:\/\/befve.com\/es\/#\/schema\/person\/ef49a1871aa7378da9d8d3cd2875d9b3"},"headline":"\u00ab Nous tablons sur des recettes nettes sup\u00e9rieures \u00e0 celles de l\u2019ann\u00e9e derni\u00e8re \u00bb par Exploitation fruiti\u00e8re Kn\u00f6bl et FreshPlaza","datePublished":"2026-06-25T12:55:10+00:00","dateModified":"2026-06-25T12:55:11+00:00","mainEntityOfPage":{"@id":"https:\/\/befve.com\/es\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\/"},"wordCount":776,"publisher":{"@id":"https:\/\/befve.com\/es\/#organization"},"image":{"@id":"https:\/\/befve.com\/es\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\/#primaryimage"},"thumbnailUrl":"https:\/\/befve.com\/wp-content\/uploads\/2026\/05\/articles-Christian-Befve-scaled.jpg","articleSection":["Non cat\u00e9goris\u00e9"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/befve.com\/es\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\/","url":"https:\/\/befve.com\/es\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\/","name":"\u00ab Nous tablons sur des recettes nettes sup\u00e9rieures \u00e0 celles de l\u2019ann\u00e9e derni\u00e8re \u00bb par Exploitation fruiti\u00e8re Kn\u00f6bl et FreshPlaza - Befve &amp; Co","isPartOf":{"@id":"https:\/\/befve.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/befve.com\/es\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\/#primaryimage"},"image":{"@id":"https:\/\/befve.com\/es\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\/#primaryimage"},"thumbnailUrl":"https:\/\/befve.com\/wp-content\/uploads\/2026\/05\/articles-Christian-Befve-scaled.jpg","datePublished":"2026-06-25T12:55:10+00:00","dateModified":"2026-06-25T12:55:11+00:00","breadcrumb":{"@id":"https:\/\/befve.com\/es\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/befve.com\/es\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/befve.com\/es\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\/#primaryimage","url":"https:\/\/befve.com\/wp-content\/uploads\/2026\/05\/articles-Christian-Befve-scaled.jpg","contentUrl":"https:\/\/befve.com\/wp-content\/uploads\/2026\/05\/articles-Christian-Befve-scaled.jpg","width":2560,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/befve.com\/es\/nous-tablons-sur-des-recettes-nettes-superieures-a-celles-de-lannee-derniere-par-exploitation-fruitiere-knobl-et-freshplaza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/befve.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00ab Nous tablons sur des recettes nettes sup\u00e9rieures \u00e0 celles de l\u2019ann\u00e9e derni\u00e8re \u00bb par Exploitation fruiti\u00e8re Kn\u00f6bl et FreshPlaza"}]},{"@type":"WebSite","@id":"https:\/\/befve.com\/es\/#website","url":"https:\/\/befve.com\/es\/","name":"Befve &Co","description":"Christian Befve expert &amp; consultant asperges","publisher":{"@id":"https:\/\/befve.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/befve.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/befve.com\/es\/#organization","name":"Befve &Co","alternateName":"Befve &Co","url":"https:\/\/befve.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/befve.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/befve.com\/wp-content\/uploads\/logo_green.svg","contentUrl":"https:\/\/befve.com\/wp-content\/uploads\/logo_green.svg","caption":"Befve &Co"},"image":{"@id":"https:\/\/befve.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/befve.com\/es\/#\/schema\/person\/ef49a1871aa7378da9d8d3cd2875d9b3","name":"Christian","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g","caption":"Christian"},"url":"https:\/\/befve.com\/es\/author\/christian\/"}]}},"_links":{"self":[{"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/posts\/266767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/comments?post=266767"}],"version-history":[{"count":1,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/posts\/266767\/revisions"}],"predecessor-version":[{"id":266768,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/posts\/266767\/revisions\/266768"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/media\/266085"}],"wp:attachment":[{"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/media?parent=266767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/categories?post=266767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/tags?post=266767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}