{"id":41575,"date":"2025-08-29T08:06:50","date_gmt":"2025-08-29T08:06:50","guid":{"rendered":"https:\/\/befve.com\/?p=41575"},"modified":"2025-08-29T08:06:51","modified_gmt":"2025-08-29T08:06:51","slug":"les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza","status":"publish","type":"post","link":"https:\/\/befve.com\/es\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\/","title":{"rendered":"Les framboises chez le producteur d&#8217;asperges Olivier Thomas par FreshPlaza"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":37267,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":21,"footnotes":""},"categories":[126,57],"tags":[],"class_list":["post-41575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-berries","category-techniques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les framboises chez le producteur d&#039;asperges Olivier Thomas par FreshPlaza - Befve &amp; Co<\/title>\n<meta name=\"description\" content=\"Olivier Thomas, Ferme du Pont d\u2019Achelles :\u00ab Face \u00e0 des ventes au ralenti, nous avons adapt\u00e9 notre production de framboises \u00bbAlors que la production de framboises en France bat son plein, les ventes ne sont pas toujours \u00e0 la hauteur des esp\u00e9rances pour les producteurs. En cause, un march\u00e9 au ralenti impact\u00e9 par les vacances estivales. \u00ab La framboise n&#039;est pas un cas \u00e0 part, beaucoup de fruits et l\u00e9gumes sont actuellement concern\u00e9s par ce manque de dynamisme au niveau commercial. C&#039;est connu, dans la r\u00e9gion au mois d&#039;ao\u00fbt le commerce est toujours calme et les fruits et l\u00e9gumes abondent souvent. Mais cette p\u00e9riode d\u00e9licate s&#039;\u00e9tendait jadis du 14 juillet au 15 ao\u00fbt alors qu&#039;aujourd&#039;hui elle commence fin juin et se termine au 15 septembre \u00bb, rapporte Olivier Thomas, g\u00e9rant de la Ferme du Pont d&#039;Achelles situ\u00e9e dans le Nord-Pas-de-Calais.Des cours tout juste r\u00e9mun\u00e9rateursFace \u00e0 ce creux dans la commercialisation, Olivier Thomas a adapt\u00e9 sa production : \u00ab Nous commen\u00e7ons la saison vers le 20 mai et la terminons aux alentours du 10 octobre. Nous avons adapt\u00e9 notre activit\u00e9 en framboise \u00e0 la r\u00e9alit\u00e9 du march\u00e9 avec un pic de production qui intervient entre mai et juin, gr\u00e2ce \u00e0 des techniques qui nous permettent de r\u00e9guler la r\u00e9colte. Quant aux cours, ils sont actuellement tout juste r\u00e9mun\u00e9rateurs \u00e0 cause de cette demande en berne et de volumes de r\u00e9colte qui s&#039;intensifient avec la chaleur actuelle \u00bb.Une comp\u00e9tition trop rudeDans un march\u00e9 fran\u00e7ais tr\u00e8s largement d\u00e9ficitaire en production nationale et principalement tourn\u00e9 vers l&#039;importation de framboises d&#039;origines \u00e9trang\u00e8res, les freins au d\u00e9veloppement de la production sont bel et bien commerciaux : \u00ab En France, nous avons la chance de savoir tout produire, au Nord comme au Sud. Mais le probl\u00e8me, c&#039;est que nous ne sommes pas \u00e9gaux au niveau de la l\u00e9gislation face \u00e0 nos voisins europ\u00e9ens, ce qui nous rend bien moins comp\u00e9titifs qu&#039;eux. Nous ne sommes pas non plus aid\u00e9s par cette guerre des prix au sein de la grande distribution qui cherche \u00e0 satisfaire un consommateur en qu\u00eate de produits pas chers. Une framboise marocaine ou espagnole est bien moins ch\u00e8re qu&#039;une framboise fran\u00e7aise mais qui est p\u00e9nalis\u00e9e par un co\u00fbt de main d&#039;\u0153uvre beaucoup plus \u00e9lev\u00e9 \u00bb.Framboise fran\u00e7aise : un gage de qualit\u00e9 gustativePourtant, malgr\u00e9 des co\u00fbts plus \u00e9lev\u00e9s, la framboise fran\u00e7aise a de nombreux atouts face \u00e0 ses concurrents : \u00ab Nous travaillons avec des vari\u00e9t\u00e9s anciennes, beaucoup plus gouteuses que celles que nous trouvons \u00e0 l&#039;import. \u00c9tant cueillies \u00e0 maturit\u00e9, elles doivent certes \u00eatre consomm\u00e9es rapidement et s&#039;exportent difficilement, mais elles offrent une qualit\u00e9 gustative remarquable et vraiment int\u00e9ressante. Consommer des framboises fran\u00e7aises, c&#039;est aussi faire vivre les campagnes qui d\u00e9pendent encore aujourd&#039;hui beaucoup de l&#039;agriculture \u00bb.Pour plus d&#039;informations :Olivier Thomas et Fran\u00e7oise ThomasLa Ferme du Pont d&#039;AchellesT\u00e9l. : 03 20 48 60 43Laferme-dupontdachelles@orange.frhttps:\/\/www.lafermedupontdachelles.frDate de publication: mar. 19 ao\u00fbt 2025\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/befve.com\/es\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les framboises chez le producteur d&#039;asperges Olivier Thomas par FreshPlaza - Befve &amp; Co\" \/>\n<meta property=\"og:description\" content=\"Olivier Thomas, Ferme du Pont d\u2019Achelles :\u00ab Face \u00e0 des ventes au ralenti, nous avons adapt\u00e9 notre production de framboises \u00bbAlors que la production de framboises en France bat son plein, les ventes ne sont pas toujours \u00e0 la hauteur des esp\u00e9rances pour les producteurs. En cause, un march\u00e9 au ralenti impact\u00e9 par les vacances estivales. \u00ab La framboise n&#039;est pas un cas \u00e0 part, beaucoup de fruits et l\u00e9gumes sont actuellement concern\u00e9s par ce manque de dynamisme au niveau commercial. C&#039;est connu, dans la r\u00e9gion au mois d&#039;ao\u00fbt le commerce est toujours calme et les fruits et l\u00e9gumes abondent souvent. Mais cette p\u00e9riode d\u00e9licate s&#039;\u00e9tendait jadis du 14 juillet au 15 ao\u00fbt alors qu&#039;aujourd&#039;hui elle commence fin juin et se termine au 15 septembre \u00bb, rapporte Olivier Thomas, g\u00e9rant de la Ferme du Pont d&#039;Achelles situ\u00e9e dans le Nord-Pas-de-Calais.Des cours tout juste r\u00e9mun\u00e9rateursFace \u00e0 ce creux dans la commercialisation, Olivier Thomas a adapt\u00e9 sa production : \u00ab Nous commen\u00e7ons la saison vers le 20 mai et la terminons aux alentours du 10 octobre. Nous avons adapt\u00e9 notre activit\u00e9 en framboise \u00e0 la r\u00e9alit\u00e9 du march\u00e9 avec un pic de production qui intervient entre mai et juin, gr\u00e2ce \u00e0 des techniques qui nous permettent de r\u00e9guler la r\u00e9colte. Quant aux cours, ils sont actuellement tout juste r\u00e9mun\u00e9rateurs \u00e0 cause de cette demande en berne et de volumes de r\u00e9colte qui s&#039;intensifient avec la chaleur actuelle \u00bb.Une comp\u00e9tition trop rudeDans un march\u00e9 fran\u00e7ais tr\u00e8s largement d\u00e9ficitaire en production nationale et principalement tourn\u00e9 vers l&#039;importation de framboises d&#039;origines \u00e9trang\u00e8res, les freins au d\u00e9veloppement de la production sont bel et bien commerciaux : \u00ab En France, nous avons la chance de savoir tout produire, au Nord comme au Sud. Mais le probl\u00e8me, c&#039;est que nous ne sommes pas \u00e9gaux au niveau de la l\u00e9gislation face \u00e0 nos voisins europ\u00e9ens, ce qui nous rend bien moins comp\u00e9titifs qu&#039;eux. Nous ne sommes pas non plus aid\u00e9s par cette guerre des prix au sein de la grande distribution qui cherche \u00e0 satisfaire un consommateur en qu\u00eate de produits pas chers. Une framboise marocaine ou espagnole est bien moins ch\u00e8re qu&#039;une framboise fran\u00e7aise mais qui est p\u00e9nalis\u00e9e par un co\u00fbt de main d&#039;\u0153uvre beaucoup plus \u00e9lev\u00e9 \u00bb.Framboise fran\u00e7aise : un gage de qualit\u00e9 gustativePourtant, malgr\u00e9 des co\u00fbts plus \u00e9lev\u00e9s, la framboise fran\u00e7aise a de nombreux atouts face \u00e0 ses concurrents : \u00ab Nous travaillons avec des vari\u00e9t\u00e9s anciennes, beaucoup plus gouteuses que celles que nous trouvons \u00e0 l&#039;import. \u00c9tant cueillies \u00e0 maturit\u00e9, elles doivent certes \u00eatre consomm\u00e9es rapidement et s&#039;exportent difficilement, mais elles offrent une qualit\u00e9 gustative remarquable et vraiment int\u00e9ressante. Consommer des framboises fran\u00e7aises, c&#039;est aussi faire vivre les campagnes qui d\u00e9pendent encore aujourd&#039;hui beaucoup de l&#039;agriculture \u00bb.Pour plus d&#039;informations :Olivier Thomas et Fran\u00e7oise ThomasLa Ferme du Pont d&#039;AchellesT\u00e9l. : 03 20 48 60 43Laferme-dupontdachelles@orange.frhttps:\/\/www.lafermedupontdachelles.frDate de publication: mar. 19 ao\u00fbt 2025\" \/>\n<meta property=\"og:url\" content=\"https:\/\/befve.com\/es\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\/\" \/>\n<meta property=\"og:site_name\" content=\"Befve &amp; Co\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-29T08:06:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T08:06:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2444\" \/>\n\t<meta property=\"og:image:height\" content=\"1020\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\\\/\"},\"author\":{\"name\":\"Christian\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#\\\/schema\\\/person\\\/ef49a1871aa7378da9d8d3cd2875d9b3\"},\"headline\":\"Les framboises chez le producteur d&#8217;asperges Olivier Thomas par FreshPlaza\",\"datePublished\":\"2025-08-29T08:06:50+00:00\",\"dateModified\":\"2025-08-29T08:06:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\\\/\"},\"wordCount\":11,\"publisher\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/articles-1.jpg\",\"articleSection\":[\"Berries\",\"Techniques\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\\\/\",\"url\":\"https:\\\/\\\/befve.com\\\/es\\\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\\\/\",\"name\":\"Les framboises chez le producteur d'asperges Olivier Thomas par FreshPlaza - Befve &amp; Co\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/articles-1.jpg\",\"datePublished\":\"2025-08-29T08:06:50+00:00\",\"dateModified\":\"2025-08-29T08:06:51+00:00\",\"description\":\"Olivier Thomas, Ferme du Pont d\u2019Achelles :\u00ab Face \u00e0 des ventes au ralenti, nous avons adapt\u00e9 notre production de framboises \u00bbAlors que la production de framboises en France bat son plein, les ventes ne sont pas toujours \u00e0 la hauteur des esp\u00e9rances pour les producteurs. En cause, un march\u00e9 au ralenti impact\u00e9 par les vacances estivales. \u00ab La framboise n'est pas un cas \u00e0 part, beaucoup de fruits et l\u00e9gumes sont actuellement concern\u00e9s par ce manque de dynamisme au niveau commercial. C'est connu, dans la r\u00e9gion au mois d'ao\u00fbt le commerce est toujours calme et les fruits et l\u00e9gumes abondent souvent. Mais cette p\u00e9riode d\u00e9licate s'\u00e9tendait jadis du 14 juillet au 15 ao\u00fbt alors qu'aujourd'hui elle commence fin juin et se termine au 15 septembre \u00bb, rapporte Olivier Thomas, g\u00e9rant de la Ferme du Pont d'Achelles situ\u00e9e dans le Nord-Pas-de-Calais.Des cours tout juste r\u00e9mun\u00e9rateursFace \u00e0 ce creux dans la commercialisation, Olivier Thomas a adapt\u00e9 sa production : \u00ab Nous commen\u00e7ons la saison vers le 20 mai et la terminons aux alentours du 10 octobre. Nous avons adapt\u00e9 notre activit\u00e9 en framboise \u00e0 la r\u00e9alit\u00e9 du march\u00e9 avec un pic de production qui intervient entre mai et juin, gr\u00e2ce \u00e0 des techniques qui nous permettent de r\u00e9guler la r\u00e9colte. Quant aux cours, ils sont actuellement tout juste r\u00e9mun\u00e9rateurs \u00e0 cause de cette demande en berne et de volumes de r\u00e9colte qui s'intensifient avec la chaleur actuelle \u00bb.Une comp\u00e9tition trop rudeDans un march\u00e9 fran\u00e7ais tr\u00e8s largement d\u00e9ficitaire en production nationale et principalement tourn\u00e9 vers l'importation de framboises d'origines \u00e9trang\u00e8res, les freins au d\u00e9veloppement de la production sont bel et bien commerciaux : \u00ab En France, nous avons la chance de savoir tout produire, au Nord comme au Sud. Mais le probl\u00e8me, c'est que nous ne sommes pas \u00e9gaux au niveau de la l\u00e9gislation face \u00e0 nos voisins europ\u00e9ens, ce qui nous rend bien moins comp\u00e9titifs qu'eux. Nous ne sommes pas non plus aid\u00e9s par cette guerre des prix au sein de la grande distribution qui cherche \u00e0 satisfaire un consommateur en qu\u00eate de produits pas chers. Une framboise marocaine ou espagnole est bien moins ch\u00e8re qu'une framboise fran\u00e7aise mais qui est p\u00e9nalis\u00e9e par un co\u00fbt de main d'\u0153uvre beaucoup plus \u00e9lev\u00e9 \u00bb.Framboise fran\u00e7aise : un gage de qualit\u00e9 gustativePourtant, malgr\u00e9 des co\u00fbts plus \u00e9lev\u00e9s, la framboise fran\u00e7aise a de nombreux atouts face \u00e0 ses concurrents : \u00ab Nous travaillons avec des vari\u00e9t\u00e9s anciennes, beaucoup plus gouteuses que celles que nous trouvons \u00e0 l'import. \u00c9tant cueillies \u00e0 maturit\u00e9, elles doivent certes \u00eatre consomm\u00e9es rapidement et s'exportent difficilement, mais elles offrent une qualit\u00e9 gustative remarquable et vraiment int\u00e9ressante. Consommer des framboises fran\u00e7aises, c'est aussi faire vivre les campagnes qui d\u00e9pendent encore aujourd'hui beaucoup de l'agriculture \u00bb.Pour plus d'informations :Olivier Thomas et Fran\u00e7oise ThomasLa Ferme du Pont d'AchellesT\u00e9l. : 03 20 48 60 43Laferme-dupontdachelles@orange.frhttps:\\\/\\\/www.lafermedupontdachelles.frDate de publication: mar. 19 ao\u00fbt 2025\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/befve.com\\\/es\\\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/articles-1.jpg\",\"contentUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/articles-1.jpg\",\"width\":2444,\"height\":1020,\"caption\":\"befve asperges\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/befve.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les framboises chez le producteur d&#8217;asperges Olivier Thomas par FreshPlaza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/befve.com\\\/es\\\/\",\"name\":\"Befve &Co\",\"description\":\"Christian Befve expert &amp; consultant asperges\",\"publisher\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/befve.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#organization\",\"name\":\"Befve &Co\",\"alternateName\":\"Befve &Co\",\"url\":\"https:\\\/\\\/befve.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/logo_green.svg\",\"contentUrl\":\"https:\\\/\\\/befve.com\\\/wp-content\\\/uploads\\\/logo_green.svg\",\"caption\":\"Befve &Co\"},\"image\":{\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/befve.com\\\/es\\\/#\\\/schema\\\/person\\\/ef49a1871aa7378da9d8d3cd2875d9b3\",\"name\":\"Christian\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g\",\"caption\":\"Christian\"},\"url\":\"https:\\\/\\\/befve.com\\\/es\\\/author\\\/christian\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les framboises chez le producteur d'asperges Olivier Thomas par FreshPlaza - Befve &amp; Co","description":"Olivier Thomas, Ferme du Pont d\u2019Achelles :\u00ab Face \u00e0 des ventes au ralenti, nous avons adapt\u00e9 notre production de framboises \u00bbAlors que la production de framboises en France bat son plein, les ventes ne sont pas toujours \u00e0 la hauteur des esp\u00e9rances pour les producteurs. En cause, un march\u00e9 au ralenti impact\u00e9 par les vacances estivales. \u00ab La framboise n'est pas un cas \u00e0 part, beaucoup de fruits et l\u00e9gumes sont actuellement concern\u00e9s par ce manque de dynamisme au niveau commercial. C'est connu, dans la r\u00e9gion au mois d'ao\u00fbt le commerce est toujours calme et les fruits et l\u00e9gumes abondent souvent. Mais cette p\u00e9riode d\u00e9licate s'\u00e9tendait jadis du 14 juillet au 15 ao\u00fbt alors qu'aujourd'hui elle commence fin juin et se termine au 15 septembre \u00bb, rapporte Olivier Thomas, g\u00e9rant de la Ferme du Pont d'Achelles situ\u00e9e dans le Nord-Pas-de-Calais.Des cours tout juste r\u00e9mun\u00e9rateursFace \u00e0 ce creux dans la commercialisation, Olivier Thomas a adapt\u00e9 sa production : \u00ab Nous commen\u00e7ons la saison vers le 20 mai et la terminons aux alentours du 10 octobre. Nous avons adapt\u00e9 notre activit\u00e9 en framboise \u00e0 la r\u00e9alit\u00e9 du march\u00e9 avec un pic de production qui intervient entre mai et juin, gr\u00e2ce \u00e0 des techniques qui nous permettent de r\u00e9guler la r\u00e9colte. Quant aux cours, ils sont actuellement tout juste r\u00e9mun\u00e9rateurs \u00e0 cause de cette demande en berne et de volumes de r\u00e9colte qui s'intensifient avec la chaleur actuelle \u00bb.Une comp\u00e9tition trop rudeDans un march\u00e9 fran\u00e7ais tr\u00e8s largement d\u00e9ficitaire en production nationale et principalement tourn\u00e9 vers l'importation de framboises d'origines \u00e9trang\u00e8res, les freins au d\u00e9veloppement de la production sont bel et bien commerciaux : \u00ab En France, nous avons la chance de savoir tout produire, au Nord comme au Sud. Mais le probl\u00e8me, c'est que nous ne sommes pas \u00e9gaux au niveau de la l\u00e9gislation face \u00e0 nos voisins europ\u00e9ens, ce qui nous rend bien moins comp\u00e9titifs qu'eux. Nous ne sommes pas non plus aid\u00e9s par cette guerre des prix au sein de la grande distribution qui cherche \u00e0 satisfaire un consommateur en qu\u00eate de produits pas chers. Une framboise marocaine ou espagnole est bien moins ch\u00e8re qu'une framboise fran\u00e7aise mais qui est p\u00e9nalis\u00e9e par un co\u00fbt de main d'\u0153uvre beaucoup plus \u00e9lev\u00e9 \u00bb.Framboise fran\u00e7aise : un gage de qualit\u00e9 gustativePourtant, malgr\u00e9 des co\u00fbts plus \u00e9lev\u00e9s, la framboise fran\u00e7aise a de nombreux atouts face \u00e0 ses concurrents : \u00ab Nous travaillons avec des vari\u00e9t\u00e9s anciennes, beaucoup plus gouteuses que celles que nous trouvons \u00e0 l'import. \u00c9tant cueillies \u00e0 maturit\u00e9, elles doivent certes \u00eatre consomm\u00e9es rapidement et s'exportent difficilement, mais elles offrent une qualit\u00e9 gustative remarquable et vraiment int\u00e9ressante. Consommer des framboises fran\u00e7aises, c'est aussi faire vivre les campagnes qui d\u00e9pendent encore aujourd'hui beaucoup de l'agriculture \u00bb.Pour plus d'informations :Olivier Thomas et Fran\u00e7oise ThomasLa Ferme du Pont d'AchellesT\u00e9l. : 03 20 48 60 43Laferme-dupontdachelles@orange.frhttps:\/\/www.lafermedupontdachelles.frDate de publication: mar. 19 ao\u00fbt 2025","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/befve.com\/es\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\/","og_locale":"es_ES","og_type":"article","og_title":"Les framboises chez le producteur d'asperges Olivier Thomas par FreshPlaza - Befve &amp; Co","og_description":"Olivier Thomas, Ferme du Pont d\u2019Achelles :\u00ab Face \u00e0 des ventes au ralenti, nous avons adapt\u00e9 notre production de framboises \u00bbAlors que la production de framboises en France bat son plein, les ventes ne sont pas toujours \u00e0 la hauteur des esp\u00e9rances pour les producteurs. En cause, un march\u00e9 au ralenti impact\u00e9 par les vacances estivales. \u00ab La framboise n'est pas un cas \u00e0 part, beaucoup de fruits et l\u00e9gumes sont actuellement concern\u00e9s par ce manque de dynamisme au niveau commercial. C'est connu, dans la r\u00e9gion au mois d'ao\u00fbt le commerce est toujours calme et les fruits et l\u00e9gumes abondent souvent. Mais cette p\u00e9riode d\u00e9licate s'\u00e9tendait jadis du 14 juillet au 15 ao\u00fbt alors qu'aujourd'hui elle commence fin juin et se termine au 15 septembre \u00bb, rapporte Olivier Thomas, g\u00e9rant de la Ferme du Pont d'Achelles situ\u00e9e dans le Nord-Pas-de-Calais.Des cours tout juste r\u00e9mun\u00e9rateursFace \u00e0 ce creux dans la commercialisation, Olivier Thomas a adapt\u00e9 sa production : \u00ab Nous commen\u00e7ons la saison vers le 20 mai et la terminons aux alentours du 10 octobre. Nous avons adapt\u00e9 notre activit\u00e9 en framboise \u00e0 la r\u00e9alit\u00e9 du march\u00e9 avec un pic de production qui intervient entre mai et juin, gr\u00e2ce \u00e0 des techniques qui nous permettent de r\u00e9guler la r\u00e9colte. Quant aux cours, ils sont actuellement tout juste r\u00e9mun\u00e9rateurs \u00e0 cause de cette demande en berne et de volumes de r\u00e9colte qui s'intensifient avec la chaleur actuelle \u00bb.Une comp\u00e9tition trop rudeDans un march\u00e9 fran\u00e7ais tr\u00e8s largement d\u00e9ficitaire en production nationale et principalement tourn\u00e9 vers l'importation de framboises d'origines \u00e9trang\u00e8res, les freins au d\u00e9veloppement de la production sont bel et bien commerciaux : \u00ab En France, nous avons la chance de savoir tout produire, au Nord comme au Sud. Mais le probl\u00e8me, c'est que nous ne sommes pas \u00e9gaux au niveau de la l\u00e9gislation face \u00e0 nos voisins europ\u00e9ens, ce qui nous rend bien moins comp\u00e9titifs qu'eux. Nous ne sommes pas non plus aid\u00e9s par cette guerre des prix au sein de la grande distribution qui cherche \u00e0 satisfaire un consommateur en qu\u00eate de produits pas chers. Une framboise marocaine ou espagnole est bien moins ch\u00e8re qu'une framboise fran\u00e7aise mais qui est p\u00e9nalis\u00e9e par un co\u00fbt de main d'\u0153uvre beaucoup plus \u00e9lev\u00e9 \u00bb.Framboise fran\u00e7aise : un gage de qualit\u00e9 gustativePourtant, malgr\u00e9 des co\u00fbts plus \u00e9lev\u00e9s, la framboise fran\u00e7aise a de nombreux atouts face \u00e0 ses concurrents : \u00ab Nous travaillons avec des vari\u00e9t\u00e9s anciennes, beaucoup plus gouteuses que celles que nous trouvons \u00e0 l'import. \u00c9tant cueillies \u00e0 maturit\u00e9, elles doivent certes \u00eatre consomm\u00e9es rapidement et s'exportent difficilement, mais elles offrent une qualit\u00e9 gustative remarquable et vraiment int\u00e9ressante. Consommer des framboises fran\u00e7aises, c'est aussi faire vivre les campagnes qui d\u00e9pendent encore aujourd'hui beaucoup de l'agriculture \u00bb.Pour plus d'informations :Olivier Thomas et Fran\u00e7oise ThomasLa Ferme du Pont d'AchellesT\u00e9l. : 03 20 48 60 43Laferme-dupontdachelles@orange.frhttps:\/\/www.lafermedupontdachelles.frDate de publication: mar. 19 ao\u00fbt 2025","og_url":"https:\/\/befve.com\/es\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\/","og_site_name":"Befve &amp; Co","article_published_time":"2025-08-29T08:06:50+00:00","article_modified_time":"2025-08-29T08:06:51+00:00","og_image":[{"width":2444,"height":1020,"url":"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg","type":"image\/jpeg"}],"author":"Christian","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Christian"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/befve.com\/es\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\/#article","isPartOf":{"@id":"https:\/\/befve.com\/es\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\/"},"author":{"name":"Christian","@id":"https:\/\/befve.com\/es\/#\/schema\/person\/ef49a1871aa7378da9d8d3cd2875d9b3"},"headline":"Les framboises chez le producteur d&#8217;asperges Olivier Thomas par FreshPlaza","datePublished":"2025-08-29T08:06:50+00:00","dateModified":"2025-08-29T08:06:51+00:00","mainEntityOfPage":{"@id":"https:\/\/befve.com\/es\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\/"},"wordCount":11,"publisher":{"@id":"https:\/\/befve.com\/es\/#organization"},"image":{"@id":"https:\/\/befve.com\/es\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\/#primaryimage"},"thumbnailUrl":"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg","articleSection":["Berries","Techniques"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/befve.com\/es\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\/","url":"https:\/\/befve.com\/es\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\/","name":"Les framboises chez le producteur d'asperges Olivier Thomas par FreshPlaza - Befve &amp; Co","isPartOf":{"@id":"https:\/\/befve.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/befve.com\/es\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\/#primaryimage"},"image":{"@id":"https:\/\/befve.com\/es\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\/#primaryimage"},"thumbnailUrl":"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg","datePublished":"2025-08-29T08:06:50+00:00","dateModified":"2025-08-29T08:06:51+00:00","description":"Olivier Thomas, Ferme du Pont d\u2019Achelles :\u00ab Face \u00e0 des ventes au ralenti, nous avons adapt\u00e9 notre production de framboises \u00bbAlors que la production de framboises en France bat son plein, les ventes ne sont pas toujours \u00e0 la hauteur des esp\u00e9rances pour les producteurs. En cause, un march\u00e9 au ralenti impact\u00e9 par les vacances estivales. \u00ab La framboise n'est pas un cas \u00e0 part, beaucoup de fruits et l\u00e9gumes sont actuellement concern\u00e9s par ce manque de dynamisme au niveau commercial. C'est connu, dans la r\u00e9gion au mois d'ao\u00fbt le commerce est toujours calme et les fruits et l\u00e9gumes abondent souvent. Mais cette p\u00e9riode d\u00e9licate s'\u00e9tendait jadis du 14 juillet au 15 ao\u00fbt alors qu'aujourd'hui elle commence fin juin et se termine au 15 septembre \u00bb, rapporte Olivier Thomas, g\u00e9rant de la Ferme du Pont d'Achelles situ\u00e9e dans le Nord-Pas-de-Calais.Des cours tout juste r\u00e9mun\u00e9rateursFace \u00e0 ce creux dans la commercialisation, Olivier Thomas a adapt\u00e9 sa production : \u00ab Nous commen\u00e7ons la saison vers le 20 mai et la terminons aux alentours du 10 octobre. Nous avons adapt\u00e9 notre activit\u00e9 en framboise \u00e0 la r\u00e9alit\u00e9 du march\u00e9 avec un pic de production qui intervient entre mai et juin, gr\u00e2ce \u00e0 des techniques qui nous permettent de r\u00e9guler la r\u00e9colte. Quant aux cours, ils sont actuellement tout juste r\u00e9mun\u00e9rateurs \u00e0 cause de cette demande en berne et de volumes de r\u00e9colte qui s'intensifient avec la chaleur actuelle \u00bb.Une comp\u00e9tition trop rudeDans un march\u00e9 fran\u00e7ais tr\u00e8s largement d\u00e9ficitaire en production nationale et principalement tourn\u00e9 vers l'importation de framboises d'origines \u00e9trang\u00e8res, les freins au d\u00e9veloppement de la production sont bel et bien commerciaux : \u00ab En France, nous avons la chance de savoir tout produire, au Nord comme au Sud. Mais le probl\u00e8me, c'est que nous ne sommes pas \u00e9gaux au niveau de la l\u00e9gislation face \u00e0 nos voisins europ\u00e9ens, ce qui nous rend bien moins comp\u00e9titifs qu'eux. Nous ne sommes pas non plus aid\u00e9s par cette guerre des prix au sein de la grande distribution qui cherche \u00e0 satisfaire un consommateur en qu\u00eate de produits pas chers. Une framboise marocaine ou espagnole est bien moins ch\u00e8re qu'une framboise fran\u00e7aise mais qui est p\u00e9nalis\u00e9e par un co\u00fbt de main d'\u0153uvre beaucoup plus \u00e9lev\u00e9 \u00bb.Framboise fran\u00e7aise : un gage de qualit\u00e9 gustativePourtant, malgr\u00e9 des co\u00fbts plus \u00e9lev\u00e9s, la framboise fran\u00e7aise a de nombreux atouts face \u00e0 ses concurrents : \u00ab Nous travaillons avec des vari\u00e9t\u00e9s anciennes, beaucoup plus gouteuses que celles que nous trouvons \u00e0 l'import. \u00c9tant cueillies \u00e0 maturit\u00e9, elles doivent certes \u00eatre consomm\u00e9es rapidement et s'exportent difficilement, mais elles offrent une qualit\u00e9 gustative remarquable et vraiment int\u00e9ressante. Consommer des framboises fran\u00e7aises, c'est aussi faire vivre les campagnes qui d\u00e9pendent encore aujourd'hui beaucoup de l'agriculture \u00bb.Pour plus d'informations :Olivier Thomas et Fran\u00e7oise ThomasLa Ferme du Pont d'AchellesT\u00e9l. : 03 20 48 60 43Laferme-dupontdachelles@orange.frhttps:\/\/www.lafermedupontdachelles.frDate de publication: mar. 19 ao\u00fbt 2025","breadcrumb":{"@id":"https:\/\/befve.com\/es\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/befve.com\/es\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/befve.com\/es\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\/#primaryimage","url":"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg","contentUrl":"https:\/\/befve.com\/wp-content\/uploads\/articles-1.jpg","width":2444,"height":1020,"caption":"befve asperges"},{"@type":"BreadcrumbList","@id":"https:\/\/befve.com\/es\/les-framboises-chez-le-producteur-dasperges-olivier-thomas-par-freshplaza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/befve.com\/es\/"},{"@type":"ListItem","position":2,"name":"Les framboises chez le producteur d&#8217;asperges Olivier Thomas par FreshPlaza"}]},{"@type":"WebSite","@id":"https:\/\/befve.com\/es\/#website","url":"https:\/\/befve.com\/es\/","name":"Befve &Co","description":"Christian Befve expert &amp; consultant asperges","publisher":{"@id":"https:\/\/befve.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/befve.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/befve.com\/es\/#organization","name":"Befve &Co","alternateName":"Befve &Co","url":"https:\/\/befve.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/befve.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/befve.com\/wp-content\/uploads\/logo_green.svg","contentUrl":"https:\/\/befve.com\/wp-content\/uploads\/logo_green.svg","caption":"Befve &Co"},"image":{"@id":"https:\/\/befve.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/befve.com\/es\/#\/schema\/person\/ef49a1871aa7378da9d8d3cd2875d9b3","name":"Christian","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aed3b721e8892b7d9bfd8295ae750fe92318b00b510c39bdb269ef3aac0241cc?s=96&d=mm&r=g","caption":"Christian"},"url":"https:\/\/befve.com\/es\/author\/christian\/"}]}},"_links":{"self":[{"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/posts\/41575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/comments?post=41575"}],"version-history":[{"count":1,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/posts\/41575\/revisions"}],"predecessor-version":[{"id":41577,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/posts\/41575\/revisions\/41577"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/media\/37267"}],"wp:attachment":[{"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/media?parent=41575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/categories?post=41575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/befve.com\/es\/wp-json\/wp\/v2\/tags?post=41575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}